{"id":47395,"date":"2024-04-11T13:36:58","date_gmt":"2024-04-11T13:36:58","guid":{"rendered":"https:\/\/www.bloomreach.com\/library\/start-the-customer-journey-right-with-an-automated-welcome-email-series"},"modified":"2024-09-23T17:41:14","modified_gmt":"2024-09-23T17:41:14","slug":"les-meilleurs-exemples-de-mails-de-bienvenue","status":"publish","type":"library","link":"https:\/\/www.bloomreach.com\/fr\/blog\/les-meilleurs-exemples-de-mails-de-bienvenue","title":{"rendered":"Les Meilleurs Exemples d&rsquo;E-mails de Bienvenue"},"content":{"rendered":"<p>En envoyant des e-mails de bienvenue aux nouveaux prospects ou aux nouveaux abonn\u00e9s, vous cr\u00e9ez une premi\u00e8re impression pour votre marque. Il va sans dire qu&rsquo;il est essentiel d&rsquo;envoyer le bon message de bienvenue afin de faire la bonne premi\u00e8re impression pour une relation longue et fructueuse.<\/p>\n<p>Comme il s&rsquo;agit de la premi\u00e8re \u00e9tape du parcours du <a href=\"https:\/\/www.bloomreach.com\/fr\/blog\/what-is-customer-lifecycle-management-and-marketing\" target=\"_blank\" rel=\"noopener noreferrer\">cycle de vie du client<\/a> apr\u00e8s qu&rsquo;une personne vous a fait confiance avec son e-mail, il est important que vous r\u00e9ussissiez la s\u00e9rie d&rsquo;e-mails de bienvenue initiale. Il existe un large \u00e9ventail de bonnes pratiques en mati\u00e8re d&rsquo;e-mails de bienvenue, mais elles se r\u00e9sument \u00e0 trois \u00e9l\u00e9ments cl\u00e9s \u00e0 retenir : <strong>le temps, le contenu et la cadence<\/strong>. Cet article aborde ces trois aspects pour vous aider \u00e0 cr\u00e9er un e-mail de bienvenue bien structur\u00e9 qui impressionnera vos abonn\u00e9s.<\/p>\n<p><img decoding=\"async\" class=\"alignnone\" src=\"https:\/\/www.bloomreach.com\/wp-content\/uploads\/2024\/05\/exp-blog-article-images-01-at-2x-1536x804-1.jpg\" alt=\"e-mails de bienvenue - exemples\" width=\"1536\" height=\"804\" \/><\/p>\n<h2>Le marketing par e-mail en chiffres<\/h2>\n<p>Avant de nous pencher sur les bonnes pratiques en mati\u00e8re d&rsquo;e-mail de bienvenue, examinons quelques statistiques sur le marketing par e-mail pour mieux comprendre l&rsquo;importance d&rsquo;un bon e-mail de bienvenue.<\/p>\n<p>Ceux d&rsquo;entre nous qui travaillent dans le marketing num\u00e9rique adorent le <a href=\"https:\/\/www.bloomreach.com\/fr\/produits\/engagement\/email-marketing\" target=\"_blank\" rel=\"noopener noreferrer\">marketing par e-mail<\/a>. Ind\u00e9pendamment de toutes les avanc\u00e9es que nous avons faites ou de la nouvelle m\u00e9thode de communication qui est tendance, l&rsquo;e-mail reste l&rsquo;un des canaux les plus importants dans l&rsquo;arsenal d&rsquo;un marketeur. C&rsquo;est pourquoi il est si important d&rsquo;envoyer le bon e-mail de bienvenue &#8211; dans la voix de votre marque &#8211; \u00e0 vos abonn\u00e9s \u00e0 l&rsquo;e-mail.<\/p>\n<p>Commen\u00e7ons par la statistique la plus \u00e9l\u00e9mentaire : le nombre d&rsquo;abonn\u00e9s actifs par canal de marketing grand public. Gardez ces chiffres \u00e0 l&rsquo;esprit lorsque vous planifiez vos communications futures avec vos clients et que vous d\u00e9terminez le canal sur lequel vous devez leur envoyer les informations les plus pertinentes.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.bloomreach.com\/wp-content\/uploads\/2024\/05\/blog_email-king_in-article_1720x1200-1.jpg\" \/><\/p>\n<p>Il y a quatre millions d&rsquo;utilisateurs d&rsquo;e-mail dans le monde. Cela signifie que quatre millions de personnes pourraient potentiellement devenir un nouvel abonn\u00e9, un client fid\u00e8le ou un client r\u00e9gulier de votre entreprise gr\u00e2ce \u00e0 votre e-mail de bienvenue.<\/p>\n<p>Si les entreprises souhaitent toucher un grand nombre de clients, les <a href=\"https:\/\/www.bloomreach.com\/fr\/bibliotheque\/livres-blancs\/recession-ready-your-marketing\" target=\"_blank\" rel=\"noopener noreferrer\">campagnes d&rsquo;e-mailing<\/a> ont le potentiel le plus \u00e9lev\u00e9 pour atteindre un grand nombre de clients. Cela s&rsquo;explique par le volume consid\u00e9rable de personnes qui s&rsquo;engagent quotidiennement avec l&rsquo;e-mail.<\/p>\n<p>L&rsquo;e-mail est le canal le plus \u00e9tabli de tout le marketing num\u00e9rique et fait tellement partie de la vie quotidienne des gens que <a href=\"https:\/\/www.statista.com\/statistics\/255080\/number-of-e-mail-users-worldwide\/\" target=\"_blank\" rel=\"noopener noreferrer\">plus de la moiti\u00e9 de la population mondiale<\/a> a une adresse e-mail qu&rsquo;elle utilise tous les jours.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.bloomreach.com\/wp-content\/uploads\/2024\/05\/blog_email-king_in-article_1720x1200-2.jpg\" \/><\/p>\n<h2>Qu&rsquo;est-ce qu&rsquo;une s\u00e9rie d&rsquo;e-mails de bienvenue automatis\u00e9s ?<\/h2>\n<p>En gardant ces chiffres \u00e0 l&rsquo;esprit, vous comprenez pourquoi les sp\u00e9cialistes du marketing par e-mail sont obs\u00e9d\u00e9s par des \u00e9l\u00e9ments tels que les lignes d&rsquo;objet des e-mails, les boutons d&rsquo;appel \u00e0 l&rsquo;action, les articles de blog les plus populaires \u00e0 inclure dans un message ou l&rsquo;endroit o\u00f9 cacher le code de r\u00e9duction dans un message ?<\/p>\n<p>Il y a beaucoup de petites choses qui entrent dans la composition d&rsquo;un mod\u00e8le d&rsquo;e-mail r\u00e9ussi et tous les d\u00e9tails comptent dans le marketing en ligne. Chez Bloomreach, nous savons que la premi\u00e8re impression est importante, c&rsquo;est pourquoi nous avons d\u00e9velopp\u00e9 la s\u00e9rie d&rsquo;e-mails de bienvenue automatis\u00e9s pour aider nos clients \u00e0 \u00e9tablir une premi\u00e8re connexion avec leurs consommateurs.<\/p>\n<p>Une s\u00e9rie d&rsquo;e-mails de bienvenue automatis\u00e9s est un ensemble d&rsquo;e-mails d\u00e9clench\u00e9s par une action du client qui signale un int\u00e9r\u00eat pour votre entreprise (par exemple, l&rsquo;ouverture d&rsquo;un compte, l&rsquo;abonnement \u00e0 une liste ou l&rsquo;inscription \u00e0 un \u00e9v\u00e9nement). Ces campagnes d&rsquo;e-mails doivent g\u00e9n\u00e9ralement transmettre ce qu&rsquo;est votre entreprise ou votre marque \u00e0 un nouvel utilisateur. Un bon e-mail de bienvenue doit \u00eatre utile, informatif et engageant et, dans la mesure du possible, moins orient\u00e9 vers la vente.<\/p>\n<h2>Bonnes pratiques pour vos e-mails de bienvenue<\/h2>\n<p>Consid\u00e9rez les trois \u00e9tapes ci-dessous dans votre parcours de prise en charge d&rsquo;un nouvel utilisateur jusqu&rsquo;\u00e0 la toute fin de mettre les clients en position de recevoir syst\u00e9matiquement des e-mails promotionnels de votre marque.<\/p>\n<ol>\n<li>Le premier e-mail est un e-mail g\u00e9n\u00e9rique qui pr\u00e9sente votre entreprise ou votre marque. Pr\u00e9sentez votre activit\u00e9, votre proposition de valeur ou ce que l&rsquo;on peut attendre de vos e-mails.<\/li>\n<li>Le deuxi\u00e8me e-mail est un petit coup de pouce pour inciter l&rsquo;abonn\u00e9 \u00e0 passer \u00e0 l&rsquo;\u00e9tape suivante du cycle de vie. Attirez-les avec vos meilleurs produits ou une d\u00e9mo de vos services.<\/li>\n<li>La troisi\u00e8me \u00e9tape est divis\u00e9e en deux branches &#8211; si une personne a d\u00e9j\u00e0 achet\u00e9 ou est pass\u00e9e \u00e0 l&rsquo;\u00e9tape suivante, encouragez-la \u00e0 se connecter sur les r\u00e9seaux sociaux ou \u00e0 installer votre application. Si quelqu&rsquo;un n&rsquo;a pas encore agi suite aux e-mails pr\u00e9c\u00e9dents, proposez une incitation pour leur donner un coup de pouce. Et faites un suivi avec le dernier e-mail demandant de se connecter sur d&rsquo;autres plateformes. <img decoding=\"async\" src=\"https:\/\/www.bloomreach.com\/wp-content\/uploads\/2024\/05\/welcome-email-series-blueprint.png\" \/><\/li>\n<\/ol>\n<h2>Pourquoi envoyer une s\u00e9rie d&rsquo;e-mails de bienvenue automatis\u00e9s ?<\/h2>\n<p>Comme un bon discours d&rsquo;ascenseur ou un chaleureux <em>\u00ab\u00a0Enchant\u00e9 de vous rencontrer\u00a0\u00bb,<\/em> une s\u00e9rie d&rsquo;e-mails de bienvenue jette les bases d&rsquo;une relation \u00e0 long terme. Ne concentrez pas toutes vos informations dans un seul e-mail. R\u00e9partissez-les plut\u00f4t dans 3 \u00e0 4 e-mails automatis\u00e9s afin que le client re\u00e7oive de petits morceaux de contenu digeste qui offrent de bons exemples de ce qu&rsquo;il peut attendre de votre marque \u00e0 l&rsquo;avenir.<\/p>\n<h2>Quand faut-il envoyer la s\u00e9rie d&rsquo;e-mails de bienvenue ?<\/h2>\n<p>Vous devriez l&rsquo;envoyer imm\u00e9diatement, ou au moins dans les premi\u00e8res 24 heures. Les gens ont une dur\u00e9e d&rsquo;attention courte, il est donc pr\u00e9f\u00e9rable d&rsquo;entrer dans leur bo\u00eete de r\u00e9ception lorsque vous \u00eates encore frais dans leur esprit. Cela les rendra plus susceptibles d&rsquo;\u00eatre int\u00e9ress\u00e9s par la r\u00e9ception de futurs e-mails de votre entreprise ou les poussera \u00e0 effectuer leur premier achat, s&rsquo;ils ne l&rsquo;ont pas encore fait.<\/p>\n<h2>Quels sont les indicateurs cl\u00e9s de performance du marketing par e-mail qui comptent pour cette s\u00e9rie ?<\/h2>\n<p>Si vous \u00eates arriv\u00e9 jusqu&rsquo;ici dans l&rsquo;article, vous comprenez l&rsquo;importance des KPI de marketing par <a href=\"https:\/\/www.bloomreach.com\/en\/blog\/email-marketing-analytics-deep-dive-metrics\" target=\"_blank\" rel=\"noopener noreferrer\">e-mail<\/a>.<\/p>\n<p>Les KPI de marketing par e-mail peuvent \u00eatre mesur\u00e9s de diff\u00e9rentes mani\u00e8res par diff\u00e9rentes parties prenantes. N&rsquo;importe quel outil de marketing par e-mail propose des dizaines d&rsquo;indicateurs de performance qui peuvent \u00eatre contr\u00f4l\u00e9s.<\/p>\n<p>Une s\u00e9rie de bienvenue est envoy\u00e9e lorsque le client est en phase d&rsquo;acquisition. Il est donc important d&rsquo;utiliser des indicateurs qui refl\u00e8tent l&rsquo;engagement et l&rsquo;\u00e9tablissement d&rsquo;une relation \u00e0 long terme.<\/p>\n<ul>\n<li>Taux d&rsquo;ouverture<\/li>\n<li>Taux de clics (CTR)<\/li>\n<li>Taux de conversion<\/li>\n<li>Taux de croissance de la liste<\/li>\n<li>Taux de d\u00e9sabonnement<\/li>\n<\/ul>\n<h2>Comment am\u00e9liorer la s\u00e9rie pour votre marque<\/h2>\n<p>Voici quelques moyens d&rsquo;aller plus loin :<\/p>\n<ul>\n<li><strong>Personnaliser en fonction de l&rsquo;activit\u00e9 de navigation :<\/strong> Entre les e-mails 1 et 2, v\u00e9rifiez si le client a eu une activit\u00e9 sur le site web. Si c&rsquo;est le cas, utilisez les donn\u00e9es de son activit\u00e9 pour personnaliser davantage votre e-mail. Par exemple, si vous \u00eates un retailer et que quelqu&rsquo;un a navigu\u00e9 dans la cat\u00e9gorie des v\u00eatements pour hommes, utilisez cette information pour proposer les meilleures ventes de v\u00eatements pour hommes ou un lien vers un article de blog sur les tendances en mati\u00e8re de v\u00eatements pour hommes.<\/li>\n<li><strong>Segmentation en fonction du type de client :<\/strong> si vous vous adressez \u00e0 diff\u00e9rents types de clients et que vous disposez de ces informations, utilisez-les pour segmenter vos e-mails de bienvenue afin de les rendre plus pertinents. Par exemple, disons que vous \u00eates un d\u00e9taillant de mat\u00e9riel informatique qui vend aux amateurs et aux propri\u00e9taires d&rsquo;entreprise. Le niveau de prix et la motivation d&rsquo;un amateur ou d&rsquo;un particulier seraient tr\u00e8s diff\u00e9rents de ceux d&rsquo;un propri\u00e9taire d&rsquo;entreprise qui se soucie davantage du ROI. Modifiez votre contenu et votre ton en cons\u00e9quence.<\/li>\n<li>Ajoutez <strong>des recommandations de produits et des liens vers des articles de blog populaires :<\/strong> ces e-mails ne se limitent pas \u00e0 la vente. Traitez votre client comme vous le feriez dans le cadre d&rsquo;une relation personnelle. Avez-vous des vid\u00e9os, des articles de blog ou d&rsquo;autres contenus utiles qui pourraient les aider \u00e0 prendre une d\u00e9cision d&rsquo;achat ? Pensez \u00e0 les inclure dans vos e-mails.<\/li>\n<li><strong>Envisagez une strat\u00e9gie omnicanale :<\/strong> pensez au-del\u00e0 de l&rsquo;e-mail pour votre s\u00e9rie de bienvenue. Examinez le sc\u00e9nario ci-dessous. Incluez des conditions pour surveiller si votre client a ouvert un e-mail. Si ce n&rsquo;est pas le cas, envisagez d&rsquo;\u00e9tendre votre s\u00e9rie de bienvenue \u00e0 d&rsquo;autres canaux tels que les SMS ou les services sociaux payants.<\/li>\n<li><strong>Incluez des <a href=\"https:\/\/www.bloomreach.com\/fr\/produits\/engagement\/experimentations-et-ab-tests\">A\/B testing<\/a>:<\/strong> aucun e-mail n&rsquo;est vraiment pr\u00eat \u00e0 l&#8217;emploi. Testez diff\u00e9rentes strat\u00e9gies pour voir ce qui fonctionne le mieux pour vous &#8211; qu&rsquo;il s&rsquo;agisse de trouver le bon canal, le bon contenu, le bon moment d&rsquo;envoi ou le bon nombre d&rsquo;e-mails.<\/li>\n<\/ul>\n<h2>Exemples d&rsquo;e-mails de bienvenue<\/h2>\n<p>Le d\u00e9taillant de meubles britannique <a href=\"https:\/\/www.dfs.co.uk\/\" target=\"_blank\" rel=\"noopener noreferrer\">DFS<\/a> a fait preuve de cr\u00e9ativit\u00e9 avec sa s\u00e9rie d&rsquo;e-mails de bienvenue automatis\u00e9s.<\/p>\n<p><a href=\"https:\/\/www.bloomreach.com\/fr\/cas-clients\/dfs-case-study\" target=\"_blank\" rel=\"noopener noreferrer\">L&rsquo;entreprise a augment\u00e9 son chiffre d&rsquo;affaires de pr\u00e8s de 4 %<\/a> gr\u00e2ce aux e-mails de bienvenue en allant plus loin et en adaptant sp\u00e9cifiquement son s\u00e9rieux de bienvenue \u00e0 son activit\u00e9 d&rsquo;ameublement et \u00e0 la mani\u00e8re dont elle souhaite \u00e9laborer les parcours clients. DFS fournit un contenu personnalis\u00e9, sp\u00e9cifique \u00e0 un produit, en fonction des produits pour lesquels elle sait que les clients sont int\u00e9ress\u00e9s, gr\u00e2ce aux donn\u00e9es qu&rsquo;elle a collect\u00e9es pr\u00e9c\u00e9demment.<\/p>\n<p>Par exemple, si la s\u00e9rie d&rsquo;e-mails de bienvenue automatis\u00e9s d\u00e9termine que le client est int\u00e9ress\u00e9 par des meubles de chambre \u00e0 coucher, le <a href=\"https:\/\/documentation.bloomreach.com\/engagement\/docs\/scenarios-1\" target=\"_blank\" rel=\"noopener noreferrer\">sc\u00e9nario Bloomreach Engagement<\/a> enverra automatiquement un guide d&rsquo;achat de meubles de chambre \u00e0 coucher au client pour faciliter les prochaines \u00e9tapes. La s\u00e9rie d&rsquo;e-mails de bienvenue encouragera ensuite les clients \u00e0 se rendre dans un magasin pour vivre une exp\u00e9rience personnelle compl\u00e8te avec le produit, exactement au bon moment dans le parcours du client.<\/p>\n<p>DFS demande aux clients \u00ab\u00a0what&rsquo;s your thing ?\u00a0\u00bb pour savoir quels meubles les int\u00e9ressent, puis <a href=\"https:\/\/www.bloomreach.com\/fr\/blog\/personnalisation-e-commerce-votre-guide-complet\">personnalise<\/a> une exp\u00e9rience client sp\u00e9cifiquement pour eux sur la base des donn\u00e9es Zero-Party collect\u00e9es. Cela permet de s&rsquo;assurer que les e-mails ne sont pas des spams pour les clients et que chaque e-mail qu&rsquo;ils re\u00e7oivent est \u00e9ducatif et en rapport avec les produits qui les int\u00e9ressent.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.bloomreach.com\/wp-content\/uploads\/2024\/05\/dfs-thumbnail.jpg\" \/><\/p>\n<p>Dans le m\u00eame ordre d&rsquo;id\u00e9es, le brasseur \u00e9cossais <a href=\"https:\/\/www.brewdog.com\/fr\" target=\"_blank\" rel=\"noopener noreferrer\">BrewDog<\/a> personnalise les mod\u00e8les d&rsquo;e-mail pour les clients en <a href=\"https:\/\/www.bloomreach.com\/fr\/blog\/brewdog-augmente-ses-revenus-avec-les-e-mails-personnalises\" target=\"_blank\" rel=\"noopener noreferrer\">modifiant la ligne d&rsquo;objet pour les diff\u00e9rents segments de clients<\/a>.<\/p>\n<p>Sur le march\u00e9 actuel, aucun client ne veut avoir l&rsquo;impression d&rsquo;\u00eatre un num\u00e9ro, ils veulent une exp\u00e9rience personnalis\u00e9e avec une marque. Quelle que soit la position des clients par rapport \u00e0 votre entreprise, la meilleure pratique consiste \u00e0 personnaliser la ligne d&rsquo;objet afin de vous assurer que vous communiquez correctement avec eux en fonction de l&rsquo;\u00e9tape du parcours client dans laquelle ils se trouvent.<\/p>\n<p><a href=\"https:\/\/www.bloomreach.com\/fr\/cas-clients\/how-brewdog-increased-revenue-using-personalized-email-campaigns-with-bloomreach\" target=\"_blank\" rel=\"noopener noreferrer\">BrewDog a augment\u00e9 son chiffre d&rsquo;affaires de pr\u00e8s de 14 %<\/a> \u00e0 partir d&rsquo;une s\u00e9quence d&rsquo;e-mails utilisant cette strat\u00e9gie.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.bloomreach.com\/wp-content\/uploads\/2024\/05\/1080x600px-brewdog-thumbnail-at-2x.png\" \/><\/p>\n<h2>Principaux enseignements<\/h2>\n<p>N&rsquo;oubliez pas : le temps, le contenu et la cadence. Envoyez votre s\u00e9rie de bienvenue d\u00e8s que possible, lorsqu&rsquo;un abonn\u00e9 pense encore \u00e0 vous. Veillez \u00e0 ce que le contenu soit informatif et utile et qu&rsquo;il corresponde \u00e0 ce qui a \u00e9t\u00e9 promis lorsque l&rsquo;abonn\u00e9 s&rsquo;est inscrit pour le recevoir.<\/p>\n<p>Enfin, au lieu d&rsquo;envoyer un seul gros e-mail, envoyez une s\u00e9rie de 3 \u00e0 4 e-mails qui vous permettront de rester en t\u00eate de la bo\u00eete de r\u00e9ception et de maintenir l&rsquo;engagement de l&rsquo;abonn\u00e9 plus longtemps. Et toujours, testez, testez, testez et r\u00e9p\u00e9tez.<\/p>\n<p>Vous souhaitez passer \u00e0 l&rsquo;\u00e9tape suivante ? <a href=\"https:\/\/www.bloomreach.com\/fr\/bibliotheque\/cas-d-utilisation\" target=\"_blank\" rel=\"noopener noreferrer\">D\u00e9couvrez comment les cas d&rsquo;utilisation Plug &amp; Play<\/a> peuvent vous aider \u00e0 g\u00e9n\u00e9rer plus de revenus avec Bloomreach Engagement.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En envoyant des e-mails de bienvenue aux nouveaux prospects ou aux nouveaux abonn\u00e9s, vous cr\u00e9ez une premi\u00e8re impression pour votre marque. Il va sans dire qu&rsquo;il est essentiel d&rsquo;envoyer le bon message de bienvenue afin de faire la bonne premi\u00e8re impression pour une relation longue et fructueuse. Comme il s&rsquo;agit de la premi\u00e8re \u00e9tape du [&hellip;]<\/p>\n","protected":false},"author":107,"featured_media":87244,"template":"","ew-regions":[],"ew-solutions":[],"library_type":[75],"library_blog_tag":[445,451],"industry":[],"channel":[521],"topic":[281],"class_list":["post-47395","library","type-library","status-publish","has-post-thumbnail","hentry","library_type-blog","library_blog_tag-marketing-automation-fr","library_blog_tag-recommandations-produits","channel-email","topic-personnalisation"],"acf":{"library_blog_banner_content":"","library_blog_banner_cta1_text":"","library_blog_banner_cta1_href":"","library_blog_banner_cta1_new_tab":false,"library_blog_banner_cta2_text":"","library_blog_banner_cta2_href":"","library_blog_banner_cta2_new_tab":false,"library_blog_banner_bg_color":"#EAF7FE","library_blog_banner_cta_text_color":"#FFF","library_blog_banner_cta_bg_color":"#019ACE","library_blog_banner_cta2_text_color":"#000","library_blog_banner_cta2_bg_color":"#FFF","library_blog_chatgpt_content":"","library_blog_chatgpt_cta_href":"","library_blog_chatgpt_cta_text":"Ask ChatGPT"},"_links":{"self":[{"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/library\/47395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/library"}],"about":[{"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/types\/library"}],"author":[{"embeddable":true,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/users\/107"}],"version-history":[{"count":1,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/library\/47395\/revisions"}],"predecessor-version":[{"id":47397,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/library\/47395\/revisions\/47397"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/media\/87244"}],"wp:attachment":[{"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/media?parent=47395"}],"wp:term":[{"taxonomy":"ew_regions","embeddable":true,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/ew-regions?post=47395"},{"taxonomy":"ew_solutions","embeddable":true,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/ew-solutions?post=47395"},{"taxonomy":"library_type","embeddable":true,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/library_type?post=47395"},{"taxonomy":"library_blog_tag","embeddable":true,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/library_blog_tag?post=47395"},{"taxonomy":"industry","embeddable":true,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/industry?post=47395"},{"taxonomy":"channel","embeddable":true,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/channel?post=47395"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/topic?post=47395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}