{"id":47383,"date":"2024-01-03T10:57:31","date_gmt":"2024-01-03T10:57:31","guid":{"rendered":"https:\/\/www.bloomreach.com\/library\/3-site-search-best-practices-for-your-commerce-brand"},"modified":"2024-09-23T16:30:48","modified_gmt":"2024-09-23T16:30:48","slug":"3-site-search-best-practices-for-your-commerce-brand","status":"publish","type":"library","link":"https:\/\/www.bloomreach.com\/fr\/blog\/3-site-search-best-practices-for-your-commerce-brand","title":{"rendered":"3 Bonnes Pratiques de Recherche sur Site pour votre E-ommerce"},"content":{"rendered":"<p>Certaines choses sont faites pour \u00eatre r\u00e9gl\u00e9es et oubli\u00e9es &#8211; le programme \u00ab\u00a0Subscribe and Save\u00a0\u00bb d&rsquo;Amazon, une mijoteuse ou un Roomba. Il vous suffit de r\u00e9gler les param\u00e8tres en fonction de vos besoins et vous n&rsquo;avez plus \u00e0 vous en pr\u00e9occuper dans un avenir proche. D&rsquo;autres choses dans la vie peuvent \u00eatre automatis\u00e9es dans une certaine mesure, mais elles ont toujours besoin d&rsquo;un peu d&rsquo;attention de temps en temps. Pour nous, la <a href=\"https:\/\/www.bloomreach.com\/en\/blog\/everything-you-need-to-know-about-search-bars-and-digital-merchandising-right-now\" target=\"_blank\" rel=\"noopener\"><u>recherche sur site e-commerce<\/u><\/a> entre dans cette derni\u00e8re cat\u00e9gorie.<\/p>\n<p>Ce que nous disons, c&rsquo;est que votre barre de recherche sur site devrait utiliser l&rsquo;<a href=\"https:\/\/www.bloomreach.com\/en\/blog\/why-self-learning-ai-is-a-game-changer-in-e-commerce\" target=\"_blank\" rel=\"noopener\"><u>intelligence artificielle (IA)<\/u><\/a> pour faire le gros du travail, mais les gestionnaires de recherche et les merchandisers ont toujours besoin de la flexibilit\u00e9 d&rsquo;une solution personnalisable. C&rsquo;est l&rsquo;une des nombreuses bonnes pratiques de recherche sur site que nous allons aborder aujourd&rsquo;hui. Mais avant d&rsquo;approfondir ce sujet, parlons de la valeur de la recherche e-commerce, de la fa\u00e7on dont l&rsquo;IA joue un r\u00f4le important et de la raison pour laquelle elle peut r\u00e9soudre certains des plus grands points de douleur de votre entreprise de commerce.<\/p>\n<h2>Quelle est la valeur de la recherche sur site e-commerce ?<\/h2>\n<p>Beaucoup d&rsquo;entre vous qui lisez ce blog connaissent probablement d\u00e9j\u00e0 la recherche sur site. Vous avez peut-\u00eatre d\u00e9j\u00e0 int\u00e9gr\u00e9 une solution de recherche sur site e-commerce, comme <a href=\"https:\/\/www.bloomreach.com\/fr\/produits\/discovery\" target=\"_blank\" rel=\"noopener\"><u>Bloomreach Discovery<\/u><\/a>, dans votre pile technologique. Une fonction de recherche est simplement un moyen d&rsquo;aider vos clients (ou acheteurs, dans le cas du march\u00e9 B2B) \u00e0 trouver exactement ce qu&rsquo;ils recherchent en les guidant vers des r\u00e9sultats pertinents.<\/p>\n<p>M\u00eame si les e-commer\u00e7ants montrent un int\u00e9r\u00eat croissant pour l&rsquo;IA et la recherche sur site, nous voyons souvent le projet \u00eatre mis de c\u00f4t\u00e9 au profit d&rsquo;autres priorit\u00e9s de l&rsquo;e-commerce, comme la publicit\u00e9 payante, l&rsquo;exp\u00e9dition \u00a0\u00bb prime-like \u00a0\u00bb ou l&rsquo;\u00e9largissement de l&rsquo;assortiment. Ces strat\u00e9gies sont importantes pour votre entreprise, mais les marques n\u00e9gligent souvent l&rsquo;impact que la recherche sur site peut avoir sur leur chiffre d&rsquo;affaires, car il est prouv\u00e9 qu&rsquo;elle augmente \u00e0 la fois la valeur moyenne des commandes (AOV) et le chiffre d&rsquo;affaires par visiteur (RPV).<\/p>\n<p><iframe src=\"https:\/\/www.youtube.com\/embed\/hdpSvLLUzoQ\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>La recherche sur site e-commerce offre de nombreux autres avantages aux entreprises et \u00e0 leurs clients :<\/p>\n<ul>\n<li><strong>Une meilleure exp\u00e9rience client<\/strong> &#8211; La recherche sur site e-commerce aidant les clients \u00e0 trouver rapidement les produits qu&rsquo;ils recherchent, elle permet d&rsquo;am\u00e9liorer l&rsquo;exp\u00e9rience client, d&rsquo;accro\u00eetre la satisfaction de la client\u00e8le et de favoriser la fid\u00e9lisation de votre entreprise.<\/li>\n<li><strong>Une meilleure personnalisation <\/strong>&#8211; Nous sommes probablement tous fatigu\u00e9s d&rsquo;entendre parler de personnalisation. En effet, malgr\u00e9 le battage m\u00e9diatique dont elle fait l&rsquo;objet depuis une dizaine d&rsquo;ann\u00e9es, elle ne semble jamais fonctionner comme elle le devrait. Mais une bonne recherche sur site peut analyser le comportement du client pour lui fournir des suggestions automatiques personnalis\u00e9es, des <a href=\"https:\/\/www.bloomreach.com\/fr\/blog\/linteret-des-recommandations-personnalisees-de-produits-en-e-commerce\" target=\"_blank\" rel=\"noopener\"><u>recommandations de produits<\/u><\/a>, etc.<\/li>\n<li><strong>R\u00e9duction des taux de rebond et des sorties de recherche <\/strong>&#8211; Les clients qui utilisent la recherche sont plus susceptibles de se convertir s&rsquo;ils peuvent facilement trouver ce qu&rsquo;ils recherchent, ce qui entra\u00eene une r\u00e9duction globale des taux de rebond et des sorties de recherche &#8211; et moins d&rsquo;argent dans les poches de vos concurrents.<\/li>\n<li><strong>Avantage concurrentiel significatif <\/strong>&#8211; Offrir des capacit\u00e9s de recherche sur site exceptionnelles peut constituer un avantage concurrentiel pour les entreprises. Si les clients associent une <a href=\"https:\/\/www.bloomreach.com\/fr\/produits\/discovery\/recherche-personnalisee\">exp\u00e9rience de recherche<\/a> fluide \u00e0 votre site e-commerce, ils seront incit\u00e9s \u00e0 d\u00e9penser plus d&rsquo;argent, \u00e0 faire des achats r\u00e9p\u00e9t\u00e9s aupr\u00e8s de votre marque et \u00e0 faire conna\u00eetre votre entreprise.<\/li>\n<\/ul>\n<p>Dans l&rsquo;ensemble, une excellente <a href=\"https:\/\/www.bloomreach.com\/fr\/produits\/discovery\/recherche-intelligente\" target=\"_blank\" rel=\"noopener\">recherche sur site<\/a> est essentielle pour offrir une <a href=\"https:\/\/www.bloomreach.com\/fr\/blog\/quest-ce-quune-plateforme-dexperience-digitale\">exp\u00e9rience digitale de<\/a> premier ordre \u00e0 vos acheteurs, ce qui permet \u00e0 votre marque de se d\u00e9marquer et d&rsquo;\u00e9tablir des relations \u00e0 long terme avec vos clients.<\/p>\n<h2>Pourquoi l&rsquo;IA devrait-elle jouer un r\u00f4le dans votre strat\u00e9gie de recherche sur site ?<\/h2>\n<p>L&rsquo;IA devient de plus en plus cruciale dans la strat\u00e9gie de recherche e-commerce des entreprises de toutes tailles, et elle devrait jouer un r\u00f4le important dans la barre de recherche du site de votre entreprise. Pour faire simple, votre site e-commerce peut fournir des r\u00e9sultats de recherche plus pr\u00e9cis en s&rsquo;appuyant sur des technologies d&rsquo;IA avanc\u00e9es, telles que l&rsquo;apprentissage machine (ML) et le <a href=\"https:\/\/www.bloomreach.com\/fr\/blog\/traitement-du-langage-naturel\" target=\"_blank\" rel=\"noopener\"><u>traitement du langage naturel<\/u><\/a> (NLP).<\/p>\n<p><img decoding=\"async\" class=\"alignnone\" src=\"https:\/\/www.bloomreach.com\/wp-content\/uploads\/2024\/05\/artificial-intelligence-breakdown-with-ml-nlp-and-deep-learning.jpg\" alt=\"L'intelligence artificielle avec la ML, la NLP et l'apprentissage profond\" width=\"1720\" height=\"922\" \/><\/p>\n<p>N&rsquo;oubliez pas qu&rsquo;un moteur de recherche e-commerce a un double objectif. D&rsquo;une part, il veille \u00e0 ce que les donn\u00e9es relatives \u00e0 vos produits soient compl\u00e8tes, correctes et coh\u00e9rentes sur tous les canaux. Deuxi\u00e8mement, il recueille des donn\u00e9es importantes sur les clients afin de simplifier le processus de recherche produits, trop important. Cela permet \u00e0 vos clients de trouver les produits qu&rsquo;ils recherchent et, plus important encore, ceux dont ils n&rsquo;avaient pas vraiment conscience d&rsquo;avoir besoin.<\/p>\n<p>\u00c0 partir de l\u00e0, l&rsquo;IA analyse le comportement des clients (par exemple, les recherches des utilisateurs, les clics et le temps de s\u00e9jour), traduisant ces donn\u00e9es en insights clients exploitables pour cr\u00e9er des r\u00e9sultats de <a href=\"https:\/\/www.bloomreach.com\/en\/blog\/the-importance-personalized-search\">recherche<\/a> et des recommandations de produits pertinents et <a href=\"https:\/\/www.bloomreach.com\/en\/blog\/the-importance-personalized-search\">personnalis\u00e9s<\/a>. La capacit\u00e9 de l&rsquo;IA \u00e0 \u00e9valuer les interactions avec les clients et \u00e0 renseigner l&rsquo;historique des achats conduit \u00e0 un engagement boost\u00e9, \u00e0 une satisfaction accrue des clients et, au final, \u00e0 des taux de conversion plus \u00e9lev\u00e9s.<\/p>\n<p>En fin de compte, l&rsquo;int\u00e9gration de l&rsquo;IA dans la <a href=\"https:\/\/www.bloomreach.com\/fr\/blog\/faites-de-la-recherche-de-produits-votre-prochaine-priorite-e-commerce\" target=\"_blank\" rel=\"noopener\"><u>strat\u00e9gie de recherche de produits<\/u><\/a> de votre entreprise de commerce est n\u00e9cessaire pour \u00eatre comp\u00e9titif dans le paysage commercial moderne et fournir les r\u00e9sultats exceptionnels que les clients attendent. Plus encore, elle permet des am\u00e9liorations \u00e9volutives de l&rsquo;exp\u00e9rience utilisateur sans intervention manuelle extr\u00eame et contribue \u00e0 l&rsquo;avantage concurrentiel de votre marque.<\/p>\n<h2>Les bonnes pratiques en mati\u00e8re de recherche sur site e-commerce<\/h2>\n<p>Maintenant que vous comprenez mieux la valeur de la recherche sur site, explorons quelques bonnes pratiques pour r\u00e9pondre aux requ\u00eates de recherche de vos clients &#8211; qui devraient toutes int\u00e9grer un aspect de l&rsquo;intelligence artificielle.<\/p>\n<h3>Placer le client au centre de l&rsquo;exp\u00e9rience<\/h3>\n<p>Dans un magasin traditionnel, des vendeurs et des employ\u00e9s professionnels peuvent aider rapidement et efficacement les clients \u00e0 trouver ce qu&rsquo;ils cherchent. Votre fonction de recherche doit servir le m\u00eame objectif sur votre site e-commerce, en comprenant l&rsquo;intention et en guidant les acheteurs vers le meilleur r\u00e9sultat possible pour leur requ\u00eate.<\/p>\n<p>C&rsquo;est pourquoi la <a href=\"https:\/\/www.bloomreach.com\/fr\/blog\/la-recherche-semantique-ses-subtilites-et-sa-valeur\" target=\"_blank\" rel=\"noopener\"><u>compr\u00e9hension s\u00e9mantique<\/u><\/a> est si importante pour votre strat\u00e9gie de recherche. Le NLP doit s\u00e9parer les produits de leurs attributs, en appliquant la compr\u00e9hension contextuelle pour d\u00e9composer les complexit\u00e9s de la signification humaine en r\u00e9sultats pertinents qui ont un sens pour le parcours d&rsquo;achat de votre client. Une fois qu&rsquo;un ensemble de produits a \u00e9t\u00e9 renvoy\u00e9 pour une requ\u00eate de recherche, l&rsquo;IA ajuste l&rsquo;ordre de ces produits pour optimiser les m\u00e9triques de l&rsquo;e-commerce.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.bloomreach.com\/wp-content\/uploads\/2024\/05\/dissection-of-search-query-for-long-sleeve-short-dress-edit.jpg\" alt=\"Dissection of Search Query for Long Sleeve Short Dress\" \/><\/p>\n<p>La ML prend ensuite les r\u00eanes, apprenant continuellement \u00e0 devenir plus intelligente pour les futurs clients. En analysant la requ\u00eate de recherche, les <a href=\"https:\/\/documentation.bloomreach.com\/discovery\/docs\/algorithm-controls\" target=\"_blank\" rel=\"noopener\"><u>algorithmes de recherche e-commerce<\/u><\/a> comprennent mieux votre client\u00e8le cibl\u00e9e et appliquent ce comportement \u00e0 l&rsquo;utilisation future. Ainsi, l&rsquo;exp\u00e9rience digitale ne cesse de s&rsquo;am\u00e9liorer, m\u00eame pour les visiteurs compl\u00e8tement anonymes, et montre \u00e0 vos clients que vous les comprenez d\u00e8s le d\u00e9part. Croyez-nous, si vous laissez l&rsquo;IA prendre la t\u00eate du processus de recherche, elle jouera \u00e9galement un r\u00f4le important dans la personnalisation de l&rsquo;exp\u00e9rience de recherche afin d&rsquo;augmenter le RPV et l&rsquo;AOV.<\/p>\n<h3>Renforcez vos donn\u00e9es e-commerce d\u00e8s que possible<\/h3>\n<p>De mauvaises donn\u00e9es sont \u00e0 peu pr\u00e8s aussi utiles que l&rsquo;absence de donn\u00e9es. Le probl\u00e8me est qu&rsquo;il existe encore beaucoup de mauvaises donn\u00e9es sur les produits et les clients &#8211; ou ce que Bloomreach appelle souvent les <a href=\"https:\/\/www.bloomreach.com\/fr\/blog\/quest-ce-que-les-donnees-du-commerce-et-pourquoi-sont-elles-importantes-pour-la-personnalisation-du-commerce-electronique\" target=\"_blank\" rel=\"noopener\"><u>\u00ab\u00a0donn\u00e9es e-commerce\u00a0\u00bb.<\/u><\/a> Le renforcement de vos donn\u00e9es e-commerce est essentiel pour l&rsquo;optimisation et la pertinence de la recherche sur site, faisant une \u00e9norme diff\u00e9rence sur la page de r\u00e9sultats de recherche \u00e0 l&rsquo;autre bout d&rsquo;une requ\u00eate.<\/p>\n<p>Et vous avez besoin de plus que des donn\u00e9es sur le parcours de navigation pour amener votre marque l\u00e0 o\u00f9 elle doit \u00eatre dans un laps de temps raisonnable. En effet, non seulement les donn\u00e9es relatives aux produits (descriptions, dimensions et prix, par exemple) renseignent vos clients sur l&rsquo;article qu&rsquo;ils ach\u00e8tent, mais elles garantissent \u00e9galement qu&rsquo;ils commandent le bon produit en fonction de leur intention, ce qui accro\u00eet encore la confiance et la satisfaction \u00e0 l&rsquo;\u00e9gard de votre marque.<\/p>\n<p>Votre entreprise peut organiser, clarifier et affiner ses donn\u00e9es \u00e0 l&rsquo;aide d&rsquo;un <a href=\"https:\/\/www.bloomreach.com\/fr\/produits\/moteur-de-donnees-clients\" target=\"_blank\" rel=\"noopener\"><u>moteur de donn\u00e9es clients<\/u><\/a> (CDE). Que vous disposiez d\u00e9j\u00e0 d&rsquo;une solution de donn\u00e9es ou que vous partiez de z\u00e9ro, un CDE introduira des donn\u00e9es commerciales organis\u00e9es dans l&rsquo;exp\u00e9rience commerciale afin d&rsquo;am\u00e9liorer la compr\u00e9hension des clients et, au final, d&rsquo;augmenter le chiffre d&rsquo;affaires.<\/p>\n<p>Une fois que vous avez d\u00e9fini, analys\u00e9 et d\u00e9ploy\u00e9 des segmentations clients qui se mettent \u00e0 jour en temps r\u00e9el, vous pouvez mieux accueillir les clients qui recherchent des produits sur votre site. Ensuite, vos \u00e9quipes applicables peuvent utiliser ces donn\u00e9es pour fa\u00e7onner votre approche du <a href=\"https:\/\/www.bloomreach.com\/fr\/produits\/discovery\/outils-de-merchandising\" target=\"_blank\" rel=\"noopener\"><u>merchandising<\/u><\/a> et des campagnes marketing. M\u00eame si vos donn\u00e9es sont loin d&rsquo;\u00eatre parfaites, les moteurs de recherche e-commerce, comme Bloomreach, peuvent combler les vides et puiser dans les donn\u00e9es historiques pour am\u00e9liorer la d\u00e9couvrabilit\u00e9, car le pixel de votre site Web continue d&rsquo;apprendre et d&rsquo;acqu\u00e9rir une compr\u00e9hension plus profonde des nuances derri\u00e8re votre entreprise particuli\u00e8re.<\/p>\n<p><img decoding=\"async\" class=\"alignnone\" src=\"https:\/\/www.bloomreach.com\/wp-content\/uploads\/2024\/05\/customer-data-engine-in-article.png\" alt=\"L'anatomie d'un moteur de donn\u00e9es clients\" width=\"1720\" height=\"847\" \/><\/p>\n<h3>Penser au-del\u00e0 de la recherche sur site e-commerce<\/h3>\n<p>La recherche sur site e-commerce n&rsquo;est que la partie \u00e9merg\u00e9e de l&rsquo;iceberg en mati\u00e8re de recherche produits. En fait, la recherche de produits se produit \u00e0 travers un large \u00e9ventail de points de contact. Offrir une exp\u00e9rience de recherche produits transparente et personnalis\u00e9e n\u00e9cessite d&rsquo;int\u00e9grer tous ces points de contact dans le parcours d&rsquo;achat global.<\/p>\n<p>Prenons l&rsquo;exemple des recommandations produits. Elles ont pour but d&rsquo;accro\u00eetre le chiffre d&rsquo;affaires de votre entreprise tout en offrant \u00e0 vos clients une meilleure exp\u00e9rience. Que vous proposiez des nouveaut\u00e9s, des produits similaires ou les meilleures ventes, vous montrez que vous comprenez votre client et ses intentions lors d&rsquo;un achat sp\u00e9cifique. Ces recommandations, personnalis\u00e9es en fonction des souhaits et des besoins uniques du client, ont de fortes chances de susciter son int\u00e9r\u00eat et de l&rsquo;encourager \u00e0 rester sur votre site apr\u00e8s avoir recherch\u00e9 le produit ou le service initial.<\/p>\n<p><img decoding=\"async\" class=\"alignnone\" src=\"https:\/\/www.bloomreach.com\/wp-content\/uploads\/2024\/05\/query-for-make-up-surfaces-recommended-products-edit.jpg\" alt=\"Demande de surfaces de maquillage Produits recommand\u00e9s\" width=\"1720\" height=\"1227\" \/><\/p>\n<p>Les <a href=\"https:\/\/www.bloomreach.com\/en\/blog\/stack-the-merchandising-odds-in-your-favor-by-doubling-down-on-the-20\" target=\"_blank\" rel=\"noopener\"><u>fonctionnalit\u00e9s de merchandising<\/u><\/a> sont \u00e9galement indispensables. Elles fournissent des insights clients, permettant \u00e0 votre marque d&rsquo;\u00e9laborer des grilles de produits adapt\u00e9es aux pr\u00e9f\u00e9rences des clients et d&rsquo;augmenter les taux de conversion et le chiffre d&rsquo;affaires. Les <a href=\"https:\/\/www.bloomreach.com\/fr\/produits\/engagement\/experimentations-et-ab-tests\">A\/B testing<\/a> sont une partie essentielle de ces capacit\u00e9s, donnant \u00e0 vos praticiens des intel pr\u00e9cieux pour prendre les meilleures d\u00e9cisions de merchandising pour votre r\u00e9sultat net.<\/p>\n<p>Pour une exp\u00e9rience de recherche produits plus compl\u00e8te, vous ne pouvez pas ignorer ces autres aspects du parcours client. N&rsquo;oubliez pas qu&rsquo;ils pr\u00e9parent tous le terrain pour la <a href=\"https:\/\/www.bloomreach.com\/fr\/blog\/personnalisation-e-commerce-votre-guide-complet\" target=\"_blank\" rel=\"noopener\"><u>personnalisation<\/u><\/a>, la segmentation et l&rsquo;optimisation &#8211; en attirant l&rsquo;attention des clients sur les produits les plus pertinents, en am\u00e9liorant l&rsquo;exp\u00e9rience d&rsquo;achat et en stimulant les ventes de votre entreprise.<\/p>\n<h2>Utilisez Bloomreach Discovery \u00e0 votre avantage<\/h2>\n<p>Les meilleurs praticiens de la recherche utilisent <a href=\"https:\/\/www.youtube.com\/watch?v=TI54VzpH-RE\" target=\"_blank\" rel=\"noopener\"><u>Bloomreach Discovery<\/u><\/a> pour offrir \u00e0 leurs clients une exp\u00e9rience de recherche de produits digne de leurs attentes du 21e si\u00e8cle. Aliment\u00e9 par une technologie d&rsquo;IA de pointe, Bloomreach Discovery permet aux professionnels de la recherche et aux merchandisers de fournir des r\u00e9sultats de recherche plus personnalis\u00e9s, plus pr\u00e9cis et plus pertinents, adapt\u00e9s aux besoins et aux pr\u00e9f\u00e9rences de chaque client. Tirez le meilleur parti de notre solution en profitant des cours de notre <a href=\"https:\/\/academy.bloomreach.com\/\" target=\"_blank\" rel=\"noopener\"><u>Acad\u00e9mie<\/u><\/a>, ou <a href=\"https:\/\/www.bloomreach.com\/fr\/bibliotheque\/livres-blancs\/recherche-sur-site-ecommerce-plus-de-revenus-des-aujourdhui\" target=\"_blank\" rel=\"noopener\"><u>explorez notre guide<\/u><\/a> sur la r\u00e9alisation de revenus maintenant <em>et<\/em> plus tard avec la recherche produits.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Certaines choses sont faites pour \u00eatre r\u00e9gl\u00e9es et oubli\u00e9es &#8211; le programme \u00ab\u00a0Subscribe and Save\u00a0\u00bb d&rsquo;Amazon, une mijoteuse ou un Roomba. Il vous suffit de r\u00e9gler les param\u00e8tres en fonction de vos besoins et vous n&rsquo;avez plus \u00e0 vous en pr\u00e9occuper dans un avenir proche. D&rsquo;autres choses dans la vie peuvent \u00eatre automatis\u00e9es dans une [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":12897,"template":"","ew-regions":[],"ew-solutions":[],"library_type":[75],"library_blog_tag":[451,434],"industry":[],"channel":[],"topic":[],"class_list":["post-47383","library","type-library","status-publish","has-post-thumbnail","hentry","library_type-blog","library_blog_tag-recommandations-produits","library_blog_tag-recherche-e-commerce"],"acf":{"library_blog_banner_content":"","library_blog_banner_cta1_text":"","library_blog_banner_cta1_href":"","library_blog_banner_cta1_new_tab":false,"library_blog_banner_cta2_text":"","library_blog_banner_cta2_href":"","library_blog_banner_cta2_new_tab":false,"library_blog_banner_bg_color":"#EAF7FE","library_blog_banner_cta_text_color":"#FFF","library_blog_banner_cta_bg_color":"#019ACE","library_blog_banner_cta2_text_color":"#000","library_blog_banner_cta2_bg_color":"#FFF","library_blog_chatgpt_content":"","library_blog_chatgpt_cta_href":"","library_blog_chatgpt_cta_text":"Ask ChatGPT"},"_links":{"self":[{"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/library\/47383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/library"}],"about":[{"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/types\/library"}],"author":[{"embeddable":true,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/users\/15"}],"version-history":[{"count":1,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/library\/47383\/revisions"}],"predecessor-version":[{"id":47385,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/library\/47383\/revisions\/47385"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/media\/12897"}],"wp:attachment":[{"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/media?parent=47383"}],"wp:term":[{"taxonomy":"ew_regions","embeddable":true,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/ew-regions?post=47383"},{"taxonomy":"ew_solutions","embeddable":true,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/ew-solutions?post=47383"},{"taxonomy":"library_type","embeddable":true,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/library_type?post=47383"},{"taxonomy":"library_blog_tag","embeddable":true,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/library_blog_tag?post=47383"},{"taxonomy":"industry","embeddable":true,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/industry?post=47383"},{"taxonomy":"channel","embeddable":true,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/channel?post=47383"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/topic?post=47383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}