{"id":28469,"date":"2023-05-09T18:25:18","date_gmt":"2023-05-09T18:25:18","guid":{"rendered":"https:\/\/www.bloomreach.com\/?post_type=library&#038;p=28469"},"modified":"2024-09-17T10:15:22","modified_gmt":"2024-09-17T10:15:22","slug":"les-meilleures-campagnes-de-marketing-pour-le-secteur-hotellerie-restauration","status":"publish","type":"library","link":"https:\/\/www.bloomreach.com\/fr\/bibliotheque\/livres-blancs\/les-meilleures-campagnes-de-marketing-pour-le-secteur-hotellerie-restauration","title":{"rendered":"Les meilleures campagnes de marketing pour le secteur h\u00f4tellerie-restauration"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Introduction<\/h2>\n\n\n\n<p>Apr\u00e8s le pic de la pand\u00e9mie, c\u2019est sans surprise que nous avons constat\u00e9 une r\u00e9surgence de l\u2019int\u00e9r\u00eat du grand public \u00e0 se rendre de nouveau au restaurant ou partir en s\u00e9jour. Le secteur de l\u2019h\u00f4tellerie-restauration a connu un retour de force extraordinaire au moment de la reprise des activit\u00e9s post-pand\u00e9mie.<\/p>\n\n\n\n<p>Si le secteur a d\u00fb surmonter de nombreux d\u00e9fis face aux changements et bouleversements r\u00e9cents, une chose reste certaine : le secteur de l\u2019h\u00f4tellerie-restauration est une industrie profond\u00e9ment tourn\u00e9e vers la client\u00e8le. La confiance, le rapport humain et les exp\u00e9riences exceptionnelles sont autant de facteurs indispensables qui contribuent \u00e0 la fid\u00e9lisation des clients.<\/p>\n\n\n\n<p>L\u2019envie de sortir et d\u2019essayer de nouvelles exp\u00e9riences constitue bien une priorit\u00e9 pour le grand public, mais les incertitudes \u00e9conomiques toujours pr\u00e9sentes am\u00e8nent les consommateurs \u00e0 faire plus attention \u00e0 leur portefeuille et ceux-ci sont plus susceptibles d\u2019aller s\u2019int\u00e9resser aux offres concurrentes qui proposent des exp\u00e9riences plus attractives et personnalis\u00e9es.<\/p>\n\n\n\n<p>Selon&nbsp;<a href=\"https:\/\/movableink.com\/resources\/audience-of-one-2022-report-getting-personalization-right?utm_source=econsultancy&amp;utm_medium=press&amp;utm_campaign=2022_press_coverage\" target=\"_blank\" rel=\"noopener\">une \u00e9tude Movable Ink<\/a>, 68 % des clients sont plus susceptibles de devenir des clients fid\u00e8les et\/ou d\u2019acheter plus si la marque interagit et favorise un rapport personnalis\u00e9 avec eux. 46 % des clients affirment que la personnalisation accro\u00eet la confiance vis-\u00e0-vis d\u2019une marque.<\/p>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"810\" style=\"aspect-ratio: 1460 \/ 810;\" width=\"1460\" autoplay loop muted preload=\"auto\" src=\"https:\/\/www.bloomreach.com\/wp-content\/uploads\/2024\/05\/01_IMG_Hospitality.mp4\" playsinline><\/video><\/figure>\n\n\n\n<p>Si vous souhaitez voir votre marque d\u2019h\u00f4tellerie ou de restauration se d\u00e9marquer de ses innombrables concurrents, il vous faut trouver&nbsp;<a href=\"https:\/\/www.bloomreach.com\/fr\/produits\/engagement?_gl=1*12c9a5p*_up*MQ..*_ga*MTQ2Mjk3MzY4Mi4xNzE3MTc4OTY3*_ga_QNZ568TB7S*MTcxNzE3ODk2NS4xLjAuMTcxNzE3ODk3MC4wLjAuMA..\" target=\"_blank\" rel=\"noreferrer noopener\">LA solution<\/a>&nbsp;qui vous aidera \u00e0 proposer des exp\u00e9riences pertinentes et personnalis\u00e9es \u00e0 vos clients en temps r\u00e9el.<\/p>\n\n\n\n<p>Ce guide pr\u00e9sente 21 cas d\u2019utilisation de marketing num\u00e9rique que les marques du secteur de l\u2019h\u00e9bergement et de la restauration exploitent pour interagir avec leurs clients dans un contexte de relance \u00e9conomique.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Les campagnes qui am\u00e9liorent les taux de conversion<\/h2>\n\n\n\n<h3 class=\"wp-block-heading has-large-font-size\"><img decoding=\"async\" style=\"width: 40px;\" src=\"https:\/\/br-files.www.bloomreach.com\/site\/binaries\/content\/gallery\/library\/whitepapers\/q123-travel-use-cases\/group-6728-at-2x.png\">\u00a0Notifications automatis\u00e9es en cas de baisse des prix<\/h3>\n\n\n\n<p><strong>L\u2019enjeu<br><\/strong>Les clients veulent le meilleur prix sans \u00eatre oblig\u00e9s de guetter la moindre mise \u00e0 jour sur votre site.<\/p>\n\n\n\n<p><strong>La solution<\/strong><br>Donnez une bonne raison aux adeptes de bons plans et aux voyageurs \u00e0 petit budget de s\u2019inscrire sur votre plateforme (et, \u00e0 terme, de devenir client) en leur offrant la possibilit\u00e9 de guetter l\u2019h\u00e9bergement de leur choix. Envoyez automatiquement et instantan\u00e9ment des notifications en cas de baisse des prix ou de nouvelles disponibilit\u00e9s. Vous pouvez aussi exploiter les donn\u00e9es relatives aux pr\u00e9f\u00e9rences de vos clients pour \u00e9mettre des recommandations pertinentes lorsque leurs premiers choix ne proposent rien de nouveau.<\/p>\n\n\n\n<p><strong>Impact<\/strong><br>Taux de conversion<br>Interaction avec le contenu<\/p>\n\n\n\n<p><strong>Canaux<\/strong><br>E-mail<br>SMS<br>Notifications push<br>Notifications au sein de l\u2019application<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-large-font-size\"><img decoding=\"async\" style=\"width: 40px;\" src=\"https:\/\/br-files.www.bloomreach.com\/site\/binaries\/content\/gallery\/library\/whitepapers\/q123-travel-use-cases\/group-6740-at-2x.png\">&nbsp;Recommandations personnalis\u00e9es gr\u00e2ce \u00e0 l\u2019IA<\/h3>\n\n\n\n<p><strong>L\u2019enjeu<br><\/strong>Les exp\u00e9riences peu pertinentes et de moindres qualit\u00e9s sont source de frustration. Ce que les clients veulent, ce sont des recommandations de produits et services qu\u2019ils seraient v\u00e9ritablement pr\u00eats \u00e0 acheter.<\/p>\n\n\n\n<p><strong>La solution<br><\/strong>Utilisez des recommandations et pr\u00e9visions g\u00e9n\u00e9r\u00e9es par IA pour proposer des h\u00f4tels, restaurants et autres services en fonction des affinit\u00e9s du client et ses actions ant\u00e9rieures, et \u00e9tablissez des correspondances avec les disponibilit\u00e9s en temps r\u00e9el. Vous pouvez \u00e9galement opter pour une m\u00e9thode qui r\u00e9pond aussi \u00e0 vos besoins : proposer des recommandations \u00e0 partir d\u2019autres clients ayant des centres d\u2019int\u00e9r\u00eat similaires.<\/p>\n\n\n\n<p><strong>Impact<\/strong><br>Taux de conversion<br>Engagement de contenu<\/p>\n\n\n\n<p><strong><strong>Canaux<\/strong><\/strong><br>Web and app<br>Email<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-large-font-size\"><img decoding=\"async\" style=\"width: 40px;\" src=\"https:\/\/br-files.www.bloomreach.com\/site\/binaries\/content\/gallery\/library\/whitepapers\/q123-travel-use-cases\/group-6745-at-2x.png\">&nbsp;Personnalisation contextualis\u00e9e<\/h3>\n\n\n\n<p><strong>L\u2019enjeu<br><\/strong>Pour offrir la meilleure exp\u00e9rience client possible, il est indispensable de v\u00e9ritablement comprendre vos clients. Qu\u2019est-ce qui les pousse \u00e0 l\u2019achat ? Le prix ? La praticit\u00e9 ? L\u2019exclusivit\u00e9 ? Si vous ne parvenez pas \u00e0 cerner le contexte de chaque client, il vous sera impossible de cr\u00e9er un rapport individuel et personnalis\u00e9 en temps r\u00e9el.<\/p>\n\n\n\n<p><strong>La solution<br><\/strong>Contrairement aux tests A\/B, la personnalisation contextualis\u00e9e s\u2019appuie sur l\u2019IA et l\u2019apprentissage automatique pour identifier l\u2019offre la plus susceptible de convertir le client. Par exemple, si vous envisagez d\u2019offrir une r\u00e9duction, un service gratuit ou une mise \u00e0 niveau, vous pouvez cr\u00e9er plusieurs banni\u00e8res avec diff\u00e9rentes offres et diff\u00e9rents contenus, puis associer chacune d\u2019entre elles \u00e0 un visiteur sp\u00e9cifique pour augmenter vos taux de conversion. La personnalisation contextualis\u00e9e offre ainsi une mani\u00e8re plus rapide d\u2019obtenir des informations et r\u00e9sultats pertinents par rapport aux tests habituels A\/B.<\/p>\n\n\n\n<p><strong>Impact<br><\/strong>Taux de conversion<br>R\u00e9alisation des objectifs<br><\/p>\n\n\n\n<p><strong>Canaux<br><\/strong>Web<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Bloomreach Engagement | Contextual Personalization\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/m8hDw7V4M0M?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading has-large-font-size\"><img decoding=\"async\" style=\"width: 40px;\" src=\"https:\/\/br-files.www.bloomreach.com\/site\/binaries\/content\/gallery\/library\/whitepapers\/q123-travel-use-cases\/group-6741-at-2x.png\">&nbsp;Newsletters personnalis\u00e9es<\/h3>\n\n\n\n<p><strong>L\u2019enjeu<br><\/strong>Les newsletters sont g\u00e9n\u00e9ralement associ\u00e9es \u00e0 des taux d\u2019engagement et de conversion plus faibles, en particulier parce qu\u2019elles sont automatis\u00e9es et envoy\u00e9es en masse sans aucune segmentation (c\u2019est le mode \u00ab batch and blast \u00bb).<\/p>\n\n\n\n<p><strong>La solution<br><\/strong>Investissez des efforts suppl\u00e9mentaires et personnalisez vos e-mails en utilisant des images et des offres bas\u00e9es sur le dernier article consult\u00e9 par le client, ses destinations pr\u00e9f\u00e9r\u00e9es et d\u2019autres donn\u00e9es de navigation. Par exemple, pour un client ayant un int\u00e9r\u00eat certain pour les offres bien-\u00eatre, vous pouvez personnaliser votre newsletter avec une image d\u2019un spa en en-t\u00eate et en mettant en avant des services ax\u00e9s sur la relaxation et le bien-\u00eatre.<\/p>\n\n\n\n<p><strong>Impact<br><\/strong>Engagement de contenu<br>Taux de conversion<\/p>\n\n\n\n<p><strong>Canaux<br><\/strong>Web<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.bloomreach.com\/en\/blog\/email-personalization-your-guide-to-better-email-marketing-campaigns\"><img decoding=\"async\" src=\"https:\/\/br-files.www.bloomreach.com\/site\/binaries\/content\/gallery\/library\/whitepapers\/q123-hospitality-use-cases\/group-6719-at-2x.png\" alt=\"\"\/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading has-large-font-size\"><img decoding=\"async\" style=\"width: 40px;\" src=\"https:\/\/br-files.www.bloomreach.com\/site\/binaries\/content\/gallery\/library\/whitepapers\/q123-travel-use-cases\/group-6752-at-2x.png\">&nbsp;Reciblage des abandons de r\u00e9servation<\/h3>\n\n\n\n<p><strong>L\u2019enjeu<br><\/strong>Vos clients songent \u00e0 effectuer une r\u00e9servation sur votre plateforme, ajoutent un article \u00e0 leur panier ou s\u2019appr\u00eatent m\u00eame \u00e0 finaliser leur r\u00e9servation. Puis d\u2019un coup\u2026 Plus rien.<\/p>\n\n\n\n<p><strong>La solution<\/strong><br>En mettant en place des&nbsp;<a href=\"https:\/\/www.bloomreach.com\/fr\/produits\/engagement\/orchestration-omnichanelle?_gl=1*1veqysw*_up*MQ..*_ga*MTQ2Mjk3MzY4Mi4xNzE3MTc4OTY3*_ga_QNZ568TB7S*MTcxNzE3ODk2NS4xLjAuMTcxNzE3ODk3MC4wLjAuMA..\" target=\"_blank\" rel=\"noreferrer noopener\">campagnes omnicanales<\/a>, vous pouvez garder le contact avec votre client et lui rappeler qu\u2019il n\u2019a pas termin\u00e9 sa r\u00e9servation. Envoyez le rappel directement par e-mail ou dirigez la personne vers une campagne payante avec du contenu cr\u00e9\u00e9 pr\u00e9cis\u00e9ment pour faciliter la conversion. Vous pouvez aussi envoyer un SMS ou des notifications push en guise de dernier rappel concernant une offre sp\u00e9ciale.<\/p>\n\n\n\n<p><strong>Impact<\/strong><br>Taux de conversion<\/p>\n\n\n\n<p><strong>Canaux<\/strong><br>E-mail<br>Annonces payantes<br>SMS<br>Notifications push<\/p>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"810\" style=\"aspect-ratio: 1460 \/ 810;\" width=\"1460\" autoplay loop muted preload=\"none\" src=\"https:\/\/www.bloomreach.com\/wp-content\/uploads\/2024\/05\/03_IMG_Hospitality.mp4\" playsinline><\/video><\/figure>\n\n\n\n<h3 class=\"wp-block-heading has-large-font-size\"><img decoding=\"async\" style=\"width: 40px;\" src=\"https:\/\/br-files.www.bloomreach.com\/site\/binaries\/content\/gallery\/library\/whitepapers\/q123-travel-use-cases\/group-6821-at-2x.png\">&nbsp;Objectifs bas\u00e9s sur les pr\u00e9dictions<\/h3>\n\n\n\n<p><strong>L\u2019enjeu<br><\/strong>Comment avoir la certitude que vous ciblez les bonnes personnes et que vous ne jetez pas vos pr\u00e9cieuses ressources publicitaires par la fen\u00eatre ?<\/p>\n\n\n\n<p><strong>La solution<br><\/strong>Gr\u00e2ce \u00e0 des mod\u00e8les de pr\u00e9diction bas\u00e9s sur l\u2019IA, vous pouvez identifier les visiteurs qui sont le plus ou le moins susceptibles de faire une r\u00e9servation. D\u00e9finissez des objectifs diff\u00e9rents pour ces deux segments. Par exemple, octroyez un bonus imm\u00e9diat aux personnes susceptibles de r\u00e9server pendant la session en cours pour faciliter la r\u00e9alisation de vos objectifs. Pour les visiteurs peu susceptibles de faire un achat pendant leur session de navigation, vous pouvez proposer un bonus pour toute inscription \u00e0 votre newsletter.<\/p>\n\n\n\n<p><strong>Impact<\/strong> <br>Taux de conversion<\/p>\n\n\n\n<p><strong>Canaux<br><\/strong>Web<\/p>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"810\" style=\"aspect-ratio: 1460 \/ 810;\" width=\"1460\" autoplay loop muted preload=\"none\" src=\"https:\/\/www.bloomreach.com\/wp-content\/uploads\/2024\/05\/04_IMG_Hospitality.mp4\" playsinline><\/video><\/figure>\n\n\n\n<h3 class=\"wp-block-heading has-large-font-size\"><img decoding=\"async\" style=\"width: 50px;\" src=\"https:\/\/br-files.www.bloomreach.com\/site\/binaries\/content\/gallery\/library\/whitepapers\/q123-travel-use-cases\/group-6818-at-2x.png\">\u00a0Donn\u00e9es \u00ab zero-party \u00bb<\/h3>\n\n\n\n<p><strong>L\u2019enjeu<\/strong><br>Les attentes en mati\u00e8re de protection de la vie priv\u00e9e sont de plus en plus exigeantes, ce qui pousse les entreprises \u00e0 adopter une meilleure approche de collecte des donn\u00e9es et d\u2019identification des pr\u00e9f\u00e9rences clients.<\/p>\n\n\n\n<p><strong>La solution<\/strong><br>Donnez aux visiteurs la possibilit\u00e9 de vous indiquer eux-m\u00eames leurs pr\u00e9f\u00e9rences. Laissez-les configurer leurs propres exp\u00e9riences en vous faisant part de ce qu\u2019ils recherchent en termes de services, gamme de prix, nombre de voyageurs, etc. L\u2019expression anglophone r\u00e9cente&nbsp;<a href=\"https:\/\/www.bloomreach.com\/fr\/blog\/limportance-des-donnees-zero-party\" target=\"_blank\" rel=\"noreferrer noopener\">\u00ab&nbsp;zero-party data&nbsp;\u00bb<\/a>&nbsp;d\u00e9signe l\u2019ensemble des donn\u00e9es que les clients fournissent de mani\u00e8re intentionnelle et proactive \u00e0 une entreprise. Utilisez&nbsp;<a href=\"https:\/\/www.bloomreach.com\/fr\/produits\/engagement\/personnalisation-web\" target=\"_blank\" rel=\"noreferrer noopener\">des outils de personnalisation con\u00e7us pour le Web ou pour une utilisation mobile<\/a>&nbsp;pour recueillir ces donn\u00e9es et ajuster vos offres en temps r\u00e9el.<\/p>\n\n\n\n<p><strong>Impact<\/strong><br>Taux de conversion<br>Engagement de contenu<\/p>\n\n\n\n<p><strong>Channels<\/strong><br>Web<br>E-mail<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-large-font-size\"><img decoding=\"async\" style=\"width: 40px;\" src=\"https:\/\/br-files.www.bloomreach.com\/site\/binaries\/content\/gallery\/library\/whitepapers\/q123-hospitality-use-cases\/group-6822-at-2x.png\">&nbsp;Choix populaires selon les donn\u00e9es de performance produit<\/h3>\n\n\n\n<p><strong>L\u2019enjeu<br><\/strong>Il arrive que les clients h\u00e9sitent parfois \u00e0 essayer de nouveaux produits sans preuve sociale pr\u00e9alable.<\/p>\n\n\n\n<p><strong>La solution<br><\/strong>Vous avez sans doute d\u00e9j\u00e0 voulu tenter une nouvelle adresse sans trop savoir si ce serait bon ? Gr\u00e2ce aux donn\u00e9es de performance des produits, apportez une r\u00e9ponse aux clients qui s\u2019interrogent. Cr\u00e9ez une liste \u00ab Choix populaires \u00bb et partagez-la aupr\u00e8s de vos clients pour leur fournir la preuve sociale n\u00e9cessaire pour promouvoir les \u00e9l\u00e9ments de votre offre qui rencontrent le plus de succ\u00e8s.<\/p>\n\n\n\n<p><strong>Impact<\/strong><br>Taux de conversion<br>Engagement de contenu<\/p>\n\n\n\n<p><strong><strong>Canaux<\/strong><\/strong><br>Email<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Les campagnes qui stimulent la valeur vie client \u00e0 long terme<\/h2>\n\n\n\n<h3 class=\"wp-block-heading has-large-font-size\"><img decoding=\"async\" style=\"width: 40px;\" src=\"https:\/\/br-files.www.bloomreach.com\/site\/binaries\/content\/gallery\/library\/whitepapers\/q123-travel-use-cases\/group-6837-at-2x.png\">&nbsp;Strat\u00e9gie d\u2019accueil<\/h3>\n\n\n\n<p><strong>L\u2019enjeu<br><\/strong>Vos prospects id\u00e9aux se sont r\u00e9cemment abonn\u00e9s, mais ne sont pas encore pr\u00eats \u00e0 cr\u00e9er un compte ou \u00e0 effectuer une r\u00e9servation.<\/p>\n\n\n\n<p><strong>La solution<br><\/strong>D\u00e9finissez un processus de communication sp\u00e9cialis\u00e9 pour accueillir vos nouveaux inscrits au sein de votre marque, avant de les inclure directement sur la liste de diffusion de votre newsletter. Ce processus de contenu soigneusement cibl\u00e9 vous permettra de marquer l\u2019esprit des clients, les incitant \u00e0 terme \u00e0 acheter chez vous. Les campagnes omnicanales vous aident \u00e0 aller au-del\u00e0 de vos campagnes de mailing. Communiquez avec des SMS\/MMS, des notifications push, des notifications au sein de l\u2019application et m\u00eame des annonces payantes pour proposer aux nouveaux venus du contenu engageant.<\/p>\n\n\n\n<p><strong>Impact<br><\/strong>Base d\u2019abonn\u00e9s dynamique<br>Taux de conversion<br>Valeur vie client<br>Engagement de contenu<\/p>\n\n\n\n<p><strong>Canaux<br><\/strong>E-mail<br>SMS<br>Notifications push<br>Notifications au sein de l\u2019application<br>Annonces payantes<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.bloomreach.com\/en\/blog\/start-the-customer-journey-right-with-an-automated-welcome-email-series\"><img decoding=\"async\" src=\"https:\/\/br-files.www.bloomreach.com\/site\/binaries\/content\/gallery\/library\/whitepapers\/q123-hospitality-use-cases\/group-6761-at-2x.png\" alt=\"\"\/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">&nbsp;&nbsp;&nbsp;<\/h3>\n\n\n\n<h3 class=\"wp-block-heading has-large-font-size\"><img decoding=\"async\" style=\"width: 40px;\" src=\"https:\/\/br-files.www.bloomreach.com\/site\/binaries\/content\/gallery\/library\/whitepapers\/q123-travel-use-cases\/group-6824-at-2x.png\">&nbsp;Optimisation des annonces via les audiences Lookalike<\/h3>\n\n\n\n<p><strong>L\u2019enjeu<br><\/strong>Vous arrivez \u00e0 augmenter votre nombre de clients pertinents, mais vous souhaitez d\u00e9sormais atteindre des prospects \u00e0 plus forte valeur ajout\u00e9e. Comment cibler votre audience id\u00e9ale ?<\/p>\n\n\n\n<p><strong>La solution<br><\/strong>Redirigez automatiquement les segments de clients \u00e0 forte valeur vie client vers les r\u00e9seaux sociaux (Facebook, Instagram et Snapchat, par exemple) et <a href=\"https:\/\/www.bloomreach.com\/fr\/produits\/engagement\/publicite-ciblage\">cr\u00e9ez des audiences similaires<\/a> pour d\u00e9nicher d\u2019autres groupes au potentiel d\u2019achat comparable. En vous appuyant sur les donn\u00e9es fournies directement par vos clients (\u00ab first-party data \u00bb), cr\u00e9ez des audiences similaires \u00e0 partir d\u2019une seed list compos\u00e9e de vos propres donn\u00e9es clients, comprenant leurs actions ant\u00e9rieures et attributs ainsi que des pr\u00e9visions.<\/p>\n\n\n\n<p><strong>Impact<br><\/strong>Taux de conversion<br>Valeur vie client<\/p>\n\n\n\n<p><strong>Canaux<br><\/strong>Publicit\u00e9s Facebook<br>Google Ads<br>Publicit\u00e9s Snapchat<\/p>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"820\" style=\"aspect-ratio: 1460 \/ 820;\" width=\"1460\" autoplay loop muted preload=\"none\" src=\"https:\/\/www.bloomreach.com\/wp-content\/uploads\/2024\/05\/05_IMG_Hospitality.mp4\" playsinline><\/video><\/figure>\n\n\n\n<h3 class=\"wp-block-heading has-large-font-size\"><img decoding=\"async\" style=\"width: 40px;\" src=\"https:\/\/br-files.www.bloomreach.com\/site\/binaries\/content\/gallery\/library\/whitepapers\/q123-travel-use-cases\/group-6826-at-2x.png\">&nbsp;Pr\u00e9diction du meilleur canal<\/h3>\n\n\n\n<p><strong>L\u2019enjeu<br><\/strong>La nature des m\u00e9dias num\u00e9riques et du parcours client 2.0 implique que vos clients interagissent avec votre marque sur une multitude de canaux et points de contact. Mais comment savoir sur quel canal se trouve votre client et avec quel canal vous aurez le plus de chances de le convertir ?<\/p>\n\n\n\n<p><strong>La solution<br><\/strong>Utilisez l\u2019IA pr\u00e9dictive pour d\u00e9terminer le canal d\u2019engagement le plus probable et ainsi am\u00e9liorer l\u2019efficacit\u00e9 de votre diffusion multicanale et augmenter vos taux de conversion. Afin de favoriser un rapport \u00e0 long terme avec vos clients, vous devez occuper une position de choix dans leur esprit et les cibler avec vos campagnes l\u00e0 o\u00f9 ils sont le plus actifs et donc le plus \u00e0 m\u00eame d\u2019interagir avec vos contenus.<\/p>\n\n\n\n<p><strong>Impact<br><\/strong>Engagement de contenu<br>Valeur vie client<\/p>\n\n\n\n<p><strong>Canaux<\/strong><br>E-mail<br>SMS<br>Notifications push<br>Notifications au sein de l\u2019application<br>Annonces payantes<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-large-font-size\"><img decoding=\"async\" style=\"width: 40px;\" src=\"https:\/\/br-files.www.bloomreach.com\/site\/binaries\/content\/gallery\/library\/whitepapers\/q123-travel-use-cases\/group-6834-at-2x.png\">&nbsp;Campagnes de mont\u00e9e en gamme et de vente crois\u00e9e<\/h3>\n\n\n\n<p><strong>L\u2019enjeu<br><\/strong>Vous avez d\u00e9j\u00e0 investi pr\u00e9cieusement dans le marketing pour inciter les clients \u00e0 choisir votre marque. Il vous faut \u00e0 pr\u00e9sent maximiser la valeur des commandes pour augmenter votre retour sur investissement.<\/p>\n\n\n\n<p><strong>La solution<br><\/strong>Cultivez votre relation avec les clients qui s\u2019appr\u00eatent \u00e0 r\u00e9server un s\u00e9jour. Envoyez-leur du contenu attractif avec des recommandations et des services additionnels tels que des surclassements de chambre d\u2019h\u00f4tel, des formules bien-\u00eatre ou des options sp\u00e9ciales pour maximiser la montant de la r\u00e9servation. La communication marketing par e-mail sera le canal le plus adapt\u00e9 pour ce type de sc\u00e9nario puisqu\u2019elle peut \u00eatre combin\u00e9e \u00e0 une communication transactionnelle par e-mail \u00e9galement.<\/p>\n\n\n\n<p><strong>Impact<br><\/strong>Valeur vie client<br>Valeur moyenne des commandes (AOV)<\/p>\n\n\n\n<p><strong>Canaux<br><\/strong>E-mail<\/p>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"810\" style=\"aspect-ratio: 1460 \/ 810;\" width=\"1460\" autoplay loop muted preload=\"none\" src=\"https:\/\/www.bloomreach.com\/wp-content\/uploads\/2024\/05\/06_IMG_Hospitality.mp4\" playsinline><\/video><\/figure>\n\n\n\n<h3 class=\"wp-block-heading has-large-font-size\"><img decoding=\"async\" style=\"width: 40px;\" src=\"https:\/\/br-files.www.bloomreach.com\/site\/binaries\/content\/gallery\/library\/whitepapers\/q123-hospitality-use-cases\/group-6829-at-2x.png\">&nbsp;Ventes incitatives de produits et services tiers<\/h3>\n\n\n\n<p><strong>L\u2019enjeu<br><\/strong>Si vous souhaitez mettre en avant certains de vos partenaires, faites-en la promotion aupr\u00e8s de vos clients sans trop d\u2019intrusion.<\/p>\n\n\n\n<p><strong>La solution<br><\/strong>Lorsque des voyageurs s\u00e9journent \u00e0 votre h\u00f4tel, il est probable qu\u2019ils souhaitent d\u00e9couvrir des activit\u00e9s ludiques, des visites et de nouveaux lieux dans la r\u00e9gion. Saisissez cette opportunit\u00e9 pour recommander certains de vos partenaires.<\/p>\n\n\n\n<p><strong>Canaux<br><\/strong>E-mail<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-large-font-size\"><img decoding=\"async\" style=\"width: 40px;\" src=\"https:\/\/br-files.www.bloomreach.com\/site\/binaries\/content\/gallery\/library\/whitepapers\/q123-hospitality-use-cases\/group-6831-at-2x.png\">&nbsp;Communication transactionnelle et marketing combin\u00e9e<\/h3>\n\n\n\n<p><strong>L\u2019enjeu<br><\/strong>Le secteur de l\u2019h\u00f4tellerie-restauration est, par nature, un secteur de services. Par cons\u00e9quent, une communication coh\u00e9rente et personnalis\u00e9e est essentielle pour offrir la meilleure exp\u00e9rience client\u00e8le.<\/p>\n\n\n\n<p><strong>La solution<br><\/strong>En utilisant la m\u00eame plateforme d\u2019e-mailing pour les communications \u00e0 la fois commerciales et marketing, vous pouvez optimiser vos communications et vous assurer que l\u2019image de marque et les mod\u00e8les sont identiques. Par ailleurs, vous pouvez rassembler dans un m\u00eame e-mail les informations importantes que le client recherche avec des offres suppl\u00e9mentaires, ce qui vous permettra de tirer parti de l\u2019engagement plus \u00e9lev\u00e9 dont b\u00e9n\u00e9ficient les e-mails commerciaux.<\/p>\n\n\n\n<p><strong>Impact<br><\/strong>Valeur vie client<br>Valeur moyenne des commandes (AOV)<\/p>\n\n\n\n<p><strong>Canaux<\/strong><br>E-mail<\/p>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"920\" style=\"aspect-ratio: 1460 \/ 920;\" width=\"1460\" autoplay loop muted preload=\"none\" src=\"https:\/\/www.bloomreach.com\/wp-content\/uploads\/2024\/05\/07_IMG_Hospitality.mp4\" playsinline><\/video><\/figure>\n\n\n\n<h3 class=\"wp-block-heading has-large-font-size\"><img decoding=\"async\" style=\"width: 40px;\" src=\"https:\/\/br-files.www.bloomreach.com\/site\/binaries\/content\/gallery\/library\/whitepapers\/q123-hospitality-use-cases\/group-6833-at-2x.png\">&nbsp;Offres saisonni\u00e8res<\/h3>\n\n\n\n<p><strong>L\u2019enjeu<br><\/strong>Les clients planifient leur s\u00e9jour \u00e0 l\u2019avance en guettant les meilleures offres pendant les vacances ou les p\u00e9riodes de f\u00eates pour \u00e9viter la d\u00e9ception face au manque de disponibilit\u00e9 ou des prix inabordables.<\/p>\n\n\n\n<p><strong>La solution<br><\/strong>Diffusez des offres saisonni\u00e8res dans votre r\u00e9gion. Par exemple, les p\u00e9riodes de No\u00ebl, les vacances d\u2019\u00e9t\u00e9 et les \u00e9v\u00e9nements culturels sont de parfaites opportunit\u00e9s pour encourager les r\u00e9servations r\u00e9currentes. Identifiez le type de fr\u00e9quentation au cours de ces \u00e9v\u00e9nements saisonniers, soit \u00e0 partir des donn\u00e9es de navigation soit \u00e0 partir des achats ant\u00e9rieurs ou consultations r\u00e9centes. Vous pourrez alors cibler ces groupes en leur pr\u00e9sentant les options disponibles et proposer les derniers tarifs applicables en pr\u00e9vision de la fr\u00e9n\u00e9sie des r\u00e9servations anticip\u00e9es aux meilleurs prix.<\/p>\n\n\n\n<p><strong>Impact<br><\/strong>Valeur vie client<br>Revenus<\/p>\n\n\n\n<p><strong>Canaux<\/strong><br>E-mail<br>Annonces payantes<br>SMS<br>Notifications push<br>Notifications au sein de l\u2019application<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Campaigns That Build Customer Loyalty<\/h2>\n\n\n\n<h3 class=\"wp-block-heading has-large-font-size\" id=\"we-re-a-studio-in-berlin-with-an-international-practice-in-architecture-urban-planning-and-interior-design-we-believe-in-sharing-knowledge-and-promoting-dialogue-to-increase-the-creative-potential-of-collaboration\" style=\"line-height:1.1\"><img decoding=\"async\" style=\"width: 40px;\" src=\"https:\/\/br-files.www.bloomreach.com\/site\/binaries\/content\/gallery\/library\/whitepapers\/q123-hospitality-use-cases\/group-5437-at-2x.png\">&nbsp;Programme de fid\u00e9lit\u00e9<\/h3>\n\n\n\n<p><strong>L\u2019enjeu<br><\/strong>Les consommateurs se tournent de mani\u00e8re croissante vers les marques qui proposent des exp\u00e9riences pertinentes \u00e0 partir de leurs donn\u00e9es personnelles. Cela dit, pour de nombreuses entreprises du secteur de l\u2019h\u00e9bergement et de la restauration, les efforts se concentrent surtout sur les exp\u00e9riences hors ligne. Afin de proposer des exp\u00e9riences \u00e0 la hauteur des attentes des clients, vous devez r\u00e9concilier les donn\u00e9es hors ligne avec les donn\u00e9es des profils clients stock\u00e9s en ligne.<\/p>\n\n\n\n<p><strong>La solution<br><\/strong>\u00c9laborez un programme de fid\u00e9lisation qui r\u00e9compense vos clients pour leur fid\u00e9lit\u00e9 et leur volont\u00e9 de vous faire part de leurs habitudes d\u2019achat. Vous pouvez, par exemple, envoyer des e-mails individualis\u00e9s par niveau de segmentation de fid\u00e9lit\u00e9. Vous pouvez aussi analyser les comportements d\u2019achat des clients et \u00e9laborer de nouvelles campagnes en ligne qui ciblent les publics pertinents avec du contenu pertinent.<\/p>\n\n\n\n<p><strong>Impact<\/strong><br>Valeur vie client<br>Taux de conversion<\/p>\n\n\n\n<p><strong>Canaux<br><\/strong>Hors ligne<br>E-mail<br>Web<br>Notifications au sein de l\u2019application<br>SMS<br>Notifications push<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-large-font-size\" id=\"we-re-a-studio-in-berlin-with-an-international-practice-in-architecture-urban-planning-and-interior-design-we-believe-in-sharing-knowledge-and-promoting-dialogue-to-increase-the-creative-potential-of-collaboration\" style=\"line-height:1.1\"><img decoding=\"async\" style=\"width: 40px;\" src=\"https:\/\/br-files.www.bloomreach.com\/site\/binaries\/content\/gallery\/library\/whitepapers\/q123-hospitality-use-cases\/group-6839-at-2x.png\"> Programmes de r\u00e9compense<\/h3>\n\n\n\n<p><strong>L\u2019enjeu<br><\/strong>De nombreux programmes de r\u00e9compense ne stimulent que trop peu l\u2019engagement client.<\/p>\n\n\n\n<p><strong>La solution<br><\/strong>Combinez vos programmes de fid\u00e9lit\u00e9 et de r\u00e9compense pour rendre l\u2019exp\u00e9rience plus ludique et diffuser du contenu encore plus personnalis\u00e9. Cr\u00e9ez de nouvelles offres pour marquer le passage de paliers de fid\u00e9lit\u00e9 ou r\u00e9compensez l\u2019anciennet\u00e9 des clients qui sont \u00e0 vos c\u00f4t\u00e9s depuis longtemps en leur proposant des offres int\u00e9ressantes proportionnelles \u00e0 leur total de points.<\/p>\n\n\n\n<p><strong>Impact<br><\/strong>Valeur vie client<\/p>\n\n\n\n<p><strong>Canaux<br><\/strong>E-mail<br>SMS<br>Notifications push<br>Notifications au sein de l\u2019application<\/p>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"810\" style=\"aspect-ratio: 1460 \/ 810;\" width=\"1460\" autoplay loop muted preload=\"none\" src=\"https:\/\/www.bloomreach.com\/wp-content\/uploads\/2024\/05\/08_IMG_Hospitality.mp4\" playsinline><\/video><\/figure>\n\n\n\n<h3 class=\"wp-block-heading has-large-font-size\"><img decoding=\"async\" style=\"width: 40px;\" src=\"https:\/\/br-files.www.bloomreach.com\/site\/binaries\/content\/gallery\/library\/whitepapers\/q123-travel-use-cases\/group-6842-at-2x.png\">&nbsp;Remerciements pour les meilleurs clients<\/h3>\n\n\n\n<p><strong>L\u2019enjeu<br><\/strong>Les clients fid\u00e8les s\u2019attendent \u00e0 une certaine reconnaissance en retour. Si vous ne r\u00e9pondez pas \u00e0 leurs attentes, vous n\u2019en ferez pas des ambassadeurs de votre enseigne.<\/p>\n\n\n\n<p><strong>La solution<br><\/strong>Remerciez vos meilleurs clients pour leur fid\u00e9lit\u00e9 avec des offres sp\u00e9ciales valables sur leur prochain s\u00e9jour. Exploitez les donn\u00e9es concernant les intervalles de r\u00e9servation moyens pour identifier le moment id\u00e9al de leur prochain s\u00e9jour.<\/p>\n\n\n\n<p><strong>Impact<br><\/strong>Engagement de contenu<br>Valeur vie client<\/p>\n\n\n\n<p><strong>Canaux<\/strong><br>E-mail<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-large-font-size\"><img decoding=\"async\" style=\"width: 40px;\" src=\"https:\/\/br-files.www.bloomreach.com\/site\/binaries\/content\/gallery\/library\/whitepapers\/q123-travel-use-cases\/group-6843-at-2x.png\">&nbsp;Campagnes de reconqu\u00eate<\/h3>\n\n\n\n<p><strong>L\u2019enjeu<br><\/strong>Lorsque vos clients n\u2019ont pas fait de r\u00e9servation depuis longtemps, le lien se perd et ils finissent par ne plus jamais interagir avec votre marque.<\/p>\n\n\n\n<p><strong>La solution<br><\/strong>Tirez parti de la segmentation RFM pour cibler les clients qui ont d\u00e9j\u00e0 achet\u00e9 chez vous par le pass\u00e9, mais qui n\u2019ont pas fait d\u2019achats depuis quelque temps. Int\u00e9ressez-vous ensuite plus en profondeur \u00e0 leurs pr\u00e9f\u00e9rences ant\u00e9rieures et actuelles en vous basant sur leur activit\u00e9 en ligne, leur engagement vis-\u00e0-vis de vos campagnes de marketing, ou leurs derniers achats. \u00c0 partir de l\u00e0, vous pourrez leur recommander des offres similaires \u00e0 celles qui les avaient int\u00e9ress\u00e9s par le pass\u00e9, mais aussi de nouvelles offres \u00e0 d\u00e9couvrir.<\/p>\n\n\n\n<p><strong>Impact<br><\/strong>Valeur vie client<br>Taux de conversion<\/p>\n\n\n\n<p><strong>Canaux<br><\/strong>E-mail<br>Web<br>Annonces payantes<\/p>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"800\" style=\"aspect-ratio: 1460 \/ 800;\" width=\"1460\" autoplay loop muted preload=\"none\" src=\"https:\/\/www.bloomreach.com\/wp-content\/uploads\/2024\/05\/09_IMG_Hospitality.mp4\" playsinline><\/video><\/figure>\n\n\n\n<h3 class=\"wp-block-heading has-large-font-size\"><img decoding=\"async\" style=\"width: 40px;\" src=\"https:\/\/br-files.www.bloomreach.com\/site\/binaries\/content\/gallery\/library\/whitepapers\/q123-travel-use-cases\/group-6845-at-2x.png\">&nbsp;Campagnes de feedback client<\/h3>\n\n\n\n<p><strong>L\u2019enjeu<br><\/strong>Si vous ne savez pas ce que vos clients ont appr\u00e9ci\u00e9 ou moins appr\u00e9ci\u00e9 lors de leur visite, toute erreur potentielle ne fera que se reproduire.<\/p>\n\n\n\n<p><strong>La solution<br><\/strong>Sollicitez l\u2019avis de vos clients \u00e0 la fin de leur s\u00e9jour pour am\u00e9liorer vos prestations. Utilisez les avis laiss\u00e9s pour cat\u00e9goriser vos clients selon leur exp\u00e9rience, puis cr\u00e9ez des segments de client\u00e8le sur la base de la note de feedback laiss\u00e9e.<\/p>\n\n\n\n<p><strong>Impact<br><\/strong>Score NPS<br>Satisfaction client<br>Valeur vie client<\/p>\n\n\n\n<p><strong>Canaux<br><\/strong>E-mail<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-large-font-size\"><img decoding=\"async\" style=\"width: 40px;\" src=\"https:\/\/br-files.www.bloomreach.com\/site\/binaries\/content\/gallery\/library\/whitepapers\/q123-travel-use-cases\/group-6847-at-2x.png\">&nbsp;Campagnes de r\u00e9engagement<\/h3>\n\n\n\n<p><strong>L\u2019enjeu<\/strong><br>Les clients inactifs depuis longtemps au sein de votre base de donn\u00e9es repr\u00e9sentent une opportunit\u00e9 int\u00e9ressante de regagner du chiffre et de fid\u00e9liser de nouveaux clients. Seulement, il n\u2019est pas toujours \u00e9vident de savoir comment les raviver.<\/p>\n\n\n\n<p><strong>La solution<br><\/strong>Si certains de vos anciens clients inactifs semblent ne plus s\u2019int\u00e9resser \u00e0 vous, lancez une campagne pour savoir pourquoi ils n\u2019interagissent plus avec vos contenus. Offrez-leur un avantage ou une r\u00e9compense pour les remercier d\u2019avoir donn\u00e9 leur avis. Passez par une orchestration omnicanale du parcours client pour atteindre ces segments sur d\u2019autres canaux (SMS, notifications push, notifications au sein de l\u2019application, campagnes d\u2019annonces payantes sur Google ou les r\u00e9seaux sociaux, etc.).<\/p>\n\n\n\n<p><strong>Impact<br><\/strong>Base d\u2019inscrits active<br>Base de donn\u00e9es saine<\/p>\n\n\n\n<p><strong>Canaux<\/strong><br>E-mail<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Conclusion: Am\u00e9liorez vos strat\u00e9gies de marketing h\u00f4telier avec Bloomreach<\/h2>\n\n\n\n<p>Voil\u00e0 donc quelques cas d\u2019utilisation du marketing digital qui produisent de bons r\u00e9sultats dans le secteur de l\u2019h\u00f4tellerie et de la restauration. Nous esp\u00e9rons que vous avez trouv\u00e9 ces id\u00e9es utiles et qu\u2019elles vous donneront de l\u2019inspiration pour \u00e9laborer vos propres campagnes.<\/p>\n\n\n\n<p>Si votre entreprise est d\u2019ores et d\u00e9j\u00e0 pr\u00eate \u00e0 mettre (toutes&nbsp;?) ces strat\u00e9gies en pratique, nous vous invitons sans attendre \u00e0 d\u00e9couvrir&nbsp;<a href=\"https:\/\/www.bloomreach.com\/fr\/produits\/engagement\" target=\"_blank\" rel=\"noreferrer noopener\">Bloomreach Engagement<\/a>. Notre puissante plateforme rassemble vos donn\u00e9es clients au sein d\u2019une vision client 360, facilitant le lancement de campagnes omnicanales sur pas moins de 13 canaux. De plus, notre IA permet de personnaliser en temps r\u00e9el les contenus et les recommandations envoy\u00e9es \u00e0 vos clients pour acc\u00e9l\u00e9rer votre retour sur investissement dans un secteur ultra-concurrentiel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Introduction Apr\u00e8s le pic de la pand\u00e9mie, c\u2019est sans surprise que nous avons constat\u00e9 une r\u00e9surgence de l\u2019int\u00e9r\u00eat du grand public \u00e0 se rendre de nouveau au restaurant ou partir en s\u00e9jour. Le secteur de l\u2019h\u00f4tellerie-restauration a connu un retour de force extraordinaire au moment de la reprise des activit\u00e9s post-pand\u00e9mie. Si le secteur a [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":28933,"template":"","ew-regions":[],"ew-solutions":[],"library_type":[515],"library_blog_tag":[445,446],"industry":[505,508],"channel":[521,542,527,540,525,529,531,523,533],"topic":[552,550,281],"class_list":["post-28469","library","type-library","status-publish","has-post-thumbnail","hentry","library_type-livres-blancs","library_blog_tag-marketing-automation-fr","library_blog_tag-personnalisation","channel-email","channel-analyses","channel-boite-de-reception-application","channel-experiences","channel-in-app","channel-publicite-et-social","channel-push-navigateur","channel-sms-mms","channel-weblayers","topic-retention-et-fidelisation","topic-ia","topic-personnalisation"],"acf":{"library_blog_banner_content":"","library_blog_banner_cta1_text":"","library_blog_banner_cta1_href":"","library_blog_banner_cta1_new_tab":false,"library_blog_banner_cta2_text":"","library_blog_banner_cta2_href":"","library_blog_banner_cta2_new_tab":false,"library_blog_banner_bg_color":"#EAF7FE","library_blog_banner_cta_text_color":"#FFF","library_blog_banner_cta_bg_color":"#019ACE","library_blog_banner_cta2_text_color":"#000","library_blog_banner_cta2_bg_color":"#FFF","library_blog_chatgpt_content":"","library_blog_chatgpt_cta_href":"","library_blog_chatgpt_cta_text":"Ask ChatGPT"},"_links":{"self":[{"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/library\/28469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/library"}],"about":[{"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/types\/library"}],"author":[{"embeddable":true,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/users\/16"}],"version-history":[{"count":1,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/library\/28469\/revisions"}],"predecessor-version":[{"id":50004,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/library\/28469\/revisions\/50004"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/media\/28933"}],"wp:attachment":[{"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/media?parent=28469"}],"wp:term":[{"taxonomy":"ew_regions","embeddable":true,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/ew-regions?post=28469"},{"taxonomy":"ew_solutions","embeddable":true,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/ew-solutions?post=28469"},{"taxonomy":"library_type","embeddable":true,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/library_type?post=28469"},{"taxonomy":"library_blog_tag","embeddable":true,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/library_blog_tag?post=28469"},{"taxonomy":"industry","embeddable":true,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/industry?post=28469"},{"taxonomy":"channel","embeddable":true,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/channel?post=28469"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/topic?post=28469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}