{"id":7693,"date":"2023-06-07T11:21:16","date_gmt":"2023-06-07T11:21:16","guid":{"rendered":"https:\/\/www.bloomreach.com\/case_study\/comment-brewdog-a-augmente-son-chiffre-daffaires-de-138-en-utilisant-des-campagnes-de-mails-personnalises-grace-a-bloomreach"},"modified":"2024-09-12T12:30:41","modified_gmt":"2024-09-12T12:30:41","slug":"how-brewdog-increased-revenue-using-personalized-email-campaigns-with-bloomreach","status":"publish","type":"case_study","link":"https:\/\/www.bloomreach.com\/fr\/cas-clients\/how-brewdog-increased-revenue-using-personalized-email-campaigns-with-bloomreach","title":{"rendered":"Comment BrewDog a augment\u00e9 son chiffre d&rsquo;affaires de 13,8 % en utilisant des campagnes d&rsquo;e-mails personnalis\u00e9s gr\u00e2ce \u00e0 Bloomreach"},"content":{"rendered":"<p><a href=\"https:\/\/www.brewdog.com\" target=\"_blank\" rel=\"noopener\">BrewDog<\/a>&nbsp;est une entreprise \u00e9cossaise de bi\u00e8re artisanale de premier ordre, fond\u00e9e en 2007 par Martin Dickie et James Watt. Aujourd&rsquo;hui, elle est la plus grande brasserie artisanale d&rsquo;Europe et est pr\u00e9sente dans 54 bars au Royaume-Uni et 44 bars au niveau international. BrewDog poss\u00e8de un portefeuille incluant des brasseries au Royaume-Uni, aux \u00c9tats-Unis, en Allemagne et en Australie.<\/p>\n","protected":false},"author":1,"featured_media":7680,"template":"","industry":[488,91],"channel":[521,540,331],"class_list":["post-7693","case_study","type-case_study","status-publish","has-post-thumbnail","hentry","channel-email","channel-experiences","channel-experiments"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/case_study\/7693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/case_study"}],"about":[{"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/types\/case_study"}],"author":[{"embeddable":true,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/case_study\/7693\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/media\/7680"}],"wp:attachment":[{"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/media?parent=7693"}],"wp:term":[{"taxonomy":"industry","embeddable":true,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/industry?post=7693"},{"taxonomy":"channel","embeddable":true,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/channel?post=7693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}