{"id":6883,"date":"2024-04-07T20:41:25","date_gmt":"2024-04-07T20:41:25","guid":{"rendered":"https:\/\/www.bloomreach.com\/case_study\/kondela-atteint-un-taux-de-conversion-de-245-grace-a-bloomreach-et-voxwise"},"modified":"2024-09-12T12:31:51","modified_gmt":"2024-09-12T12:31:51","slug":"kondela","status":"publish","type":"case_study","link":"https:\/\/www.bloomreach.com\/fr\/cas-clients\/kondela","title":{"rendered":"Kondela atteint un taux de conversion de 24,5 % gr\u00e2ce \u00e0 Bloomreach et Voxwise"},"content":{"rendered":"<p><style type=\"text\/css\"><!--td {border: 1px solid #cccccc;}br {mso-data-placement:same-cell;}-->\n<\/style>\n<p><a href=\"http:\/\/www.kondela.sk\/\" target=\"_blank\" rel=\"noopener\">Kondela<\/a> est un d\u00e9taillant de meubles qui op\u00e8re en Europe centrale depuis plus de 30 ans. L&rsquo;entreprise dispose d&rsquo;une boutique en ligne en plein essor et de magasins dans plusieurs pays d&rsquo;Europe centrale. Kondela propose \u00e0 ses clients une large gamme de meubles, de produits pour la maison et d&rsquo;accessoires, tout en veillant \u00e0 ce que les achats soient faciles.<\/p>\n","protected":false},"author":1,"featured_media":6870,"template":"","industry":[86,511,492],"channel":[542,332,521,540,270],"class_list":["post-6883","case_study","type-case_study","status-publish","has-post-thumbnail","hentry","channel-analyses","channel-analytics","channel-email","channel-experiences","channel-in-app"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/case_study\/6883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/case_study"}],"about":[{"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/types\/case_study"}],"author":[{"embeddable":true,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/case_study\/6883\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/media\/6870"}],"wp:attachment":[{"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/media?parent=6883"}],"wp:term":[{"taxonomy":"industry","embeddable":true,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/industry?post=6883"},{"taxonomy":"channel","embeddable":true,"href":"https:\/\/www.bloomreach.com\/fr\/wp-json\/wp\/v2\/channel?post=6883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}