{"id":2260,"date":"2024-05-09T13:58:39","date_gmt":"2024-05-09T13:58:39","guid":{"rendered":"https:\/\/www.bloomreach.com\/legal\/bloomreach-privacy-notice-2"},"modified":"2025-02-28T14:47:20","modified_gmt":"2025-02-28T14:47:20","slug":"bloomreach-privacy-notice","status":"publish","type":"legal","link":"https:\/\/www.bloomreach.com\/de\/legal\/bloomreach-privacy-notice","title":{"rendered":"Datenschutzhinweis auf der Website"},"content":{"rendered":"<section class=\"section pt-50 pb-20 py-md-120 pt-lg-120 pb-lg-4 \">\n<div class=\"container\">\n<div class=\"row\">\n<div class=\"col-lg-12\">\n<h2 class=\"h1\">Website-Datenschutzhinweis<\/h2>\n<div>\n<p><strong>Zuletzt aktualisiert: 18. Mai 2018<\/strong><\/p>\n<p>BloomReach, Inc. und seine Tochtergesellschaften (&#8222;<strong>BloomReach<\/strong>&#8222;, &#8222;<strong>wir<\/strong>&#8220; und &#8222;<strong>unser<\/strong>&#8222;)<br \/>\nnehmen den Datenschutz sehr ernst. Die Website-Datenschutzhinweise (&#8222;<strong>Datenschutzhinweise<\/strong>&#8222;)<br \/>\nerl\u00e4utert, wer wir sind, wie wir personenbezogene Daten \u00fcber Sie sammeln, weitergeben und verwenden und wie Sie Ihre Datenschutzrechte wahrnehmen k\u00f6nnen.<\/p>\n<p>Dieser Datenschutzhinweis gilt nur f\u00fcr personenbezogene Daten, die wir im Rahmen unserer \u00fcblichen Gesch\u00e4ftst\u00e4tigkeit<br \/>\nerheben, einschlie\u00dflich \u00fcber unsere Websites (wie <a href=\"https:\/\/www.bloomreach.com\/de\">https:\/\/www.bloomreach.com\/de<\/a>)<br \/>\n(zusammenfassend die &#8222;<strong>Websites<\/strong>&#8222;), mittels Produktfeedback und Umfragen sowie in Zusammenhang mit unseren Veranstaltungen, Verkaufs- und Marketingaktivit\u00e4ten.<\/p>\n<p>Pers\u00f6nliche Daten, die wir im Zuge einer Kontoerstellung bei BloomReach erheben, bei einer Nutzung unsere Produkte und Dienstleistungen,<br \/>\nsowie bei einer anderweitigen Interaktion, k\u00f6nnen Sie in unserer<br \/>\nDatenschutzerkl\u00e4rung f\u00fcr Dienstleistungen <a href=\"https:\/\/www.bloomreach.com\/de\/datenschutz-bei-bloomreach\">hier einsehen<\/a>;<\/p>\n<p>Wenn Sie Fragen zu dieser Datenschutzerkl\u00e4rung haben, <a href=\"#Contact Us\">kontaktieren Sie uns bitte<br \/>\nunter den unten angegebenen Kontaktdaten.<\/a>.<\/p>\n<h3>Quick links<\/h3>\n<p>Wir empfehlen Ihnen, diese Datenschutzerkl\u00e4rung vollst\u00e4ndig zu lesen, um sicherzustellen, dass Sie umfassend informiert sind. Wenn Sie allerdings nur einen bestimmten Abschnitt dieser Datenschutzerkl\u00e4rung einsehen m\u00f6chten, k\u00f6nnen Sie auf die unten stehenden Links klicken.<\/p>\n<p><a href=\"#Who we are\">Wer wir sind<\/a><\/p>\n<p><a href=\"#What information do we collect and why?\">Welche Informationen sammeln wir und warum?<\/a><\/p>\n<p><a href=\"#Who do we share your personal information with?\">Mit wem teilen wir Ihre pers\u00f6nlichen Informationen\/Daten?<\/a><\/p>\n<p><a href=\"#Cookies and similar tracking technology\">Cookies und \u00e4hnliche Tracking-Technologien<\/a><\/p>\n<p><a href=\"#Legal basis for processing personal information (EEA residents only)\">Rechtsgrundlage f\u00fcr die Verarbeitung personenbezogener Daten (nur f\u00fcr EWR-B\u00fcrger)<\/a><\/p>\n<p><a href=\"#International data transfers\">Internationale Daten\u00fcbermittlung<\/a><\/p>\n<p><a href=\"#Data Retention\">Datenaufbewahrung<\/a><\/p>\n<p><a href=\"#Your data protection rights\">Ihre Datenschutzrechte<\/a><\/p>\n<p><a href=\"#Children\">Kinder<\/a><\/p>\n<p><a href=\"#Changes to our Privacy Notice\">\u00c4nderungen unseres Datenschutzhinweises<\/a><\/p>\n<p><a href=\"#Contact Us\">Kontaktieren Sie uns \u00a0<\/a><\/p>\n<h3><a id=\"Who we are\" name=\"Who we are\"><\/a>Wer wir sind<\/h3>\n<p>BloomReach ist ein globales Unternehmen mit Hauptsitz in den USA und Tochtergesellschaften,<br \/>\nB\u00fcros und\/oder Mitarbeitern in den Niederlanden, Gro\u00dfbritannien, Deutschland und Indien.<br \/>\nWir stellen Verlagen, Einzelh\u00e4ndlern, Websites und anderen (unseren &#8222;Kunden&#8220;) Tools, Analyse- und Personalisierungsdienste zur Verf\u00fcgung,<br \/>\ndie unseren Kunden helfen, Inhalte zu entwickeln und zu ver\u00f6ffentlichen und ihre Kunden dabei unterst\u00fctzen, die gew\u00fcnschten Inhalte zu finden.<br \/>\nMehr \u00fcber BloomReach erfahren <a href=\"https:\/\/www.bloomreach.com\/de\">Sie hier<\/a>.<\/p>\n<h3><a id=\"What information do we collect and why?\" name=\"What information do we collect and why?\"><\/a>Welche Informationen sammeln wir und warum?<\/h3>\n<p>Die personenbezogenen Daten, die wir \u00fcber Sie sammeln, lassen sich grob in die folgende Kategorien einteilen:<\/p>\n<p><strong>Informationen, die Sie uns freiwillig zur Verf\u00fcgung stellen:<\/strong> In bestimmten Bereichen unserer Website bitten wir Sie um die freiwillige Angabe personenbezogener Daten: So bitten wir Sie beispielsweise um Ihre Kontaktdaten (wie Ihren Namen, Ihre E-Mail-Adresse und Ihre Telefonnummer), wenn Sie Informationen \u00fcber unsere Produkte und Dienstleistungen anfordern, Zugang zu einer Demo oder zu Online-Schulungsmaterialien beantragen, Marketingmitteilungen (wie Newsletter) von uns abonnieren und\/oder anderweitig Anfragen an uns richten.<\/p>\n<p>Wir k\u00f6nnen auch offline personenbezogene Daten von Ihnen erheben, z. B. wenn Sie an einer unserer Veranstaltungen teilnehmen oder w\u00e4hrend eines Telefonats mit einem Vertriebsmitarbeiter. Die pers\u00f6nlichen Daten, um die Sie gebeten werden, und die Gr\u00fcnde, warum Sie um diese Daten gebeten werden, werden Ihnen zu dem Zeitpunkt mitgeteilt, an dem wir Sie um die Angabe Ihrer pers\u00f6nlichen Daten bitten.<\/p>\n<p>Wir werden Sie auch vor der Erhebung dar\u00fcber informieren, ob die Bereitstellung der personenbezogenen Daten, die wir erfassen, obligatorisch ist oder auf freiwilliger Basis erfolgen kann, sowie welche etwaigen Auswirkungen es gegebenenfalls nach sich zieht, falls Sie diese Informationen nicht bereitstellen.<\/p>\n<p><em>Die von uns erfassten personenbezogenen Daten k\u00f6nnen Kontaktinformationen wie Ihren Namen, Ihre Adresse, Telefonnummer oder E-Mail-Adresse sowie Kontaktpr\u00e4ferenzen enthalten. Sie k\u00f6nnen auch berufliche Informationen einschlie\u00dfen, wie z. B. Ihre Berufsbezeichnung, Abteilung oder Funktion, sowie die Art Ihrer Anfrage oder Mitteilung. Wir erfassen auch Informationen, die Sie uns beim Ausf\u00fcllen von Freitextfeldern in unseren Formularen zur Verf\u00fcgung stellen (z. B. f\u00fcr die Anmeldung zu Veranstaltungen, Produktfeedback oder Umfragen). \u00a0<\/em><\/p>\n<p><u>Beispiele daf\u00fcr, wie wir diese Informationen verwenden, sind:<\/u><\/p>\n<ul>\n<li>Um auf Ihre Anfragen zu antworten oder Ihnen die von Ihnen angeforderten Informationen zukommen zu lassen.<\/li>\n<li>Um Ihnen administrative oder kontobezogene Informationen zu senden.<\/li>\n<li>Um Sie \u00fcber Aktualisierungen des Dienstes zu informieren.<\/li>\n<li>Um die Website zu pflegen und auf Ihre Bed\u00fcrfnisse abzustimmen.<\/li>\n<li>Um mit Ihnen per Post, Telefon und\/oder E-Mail Kontakt aufzunehmen, Ihnen Marketing- und Werbeinhalte zukommen zu lassen (in \u00dcbereinstimmung mit Ihren Marketingpr\u00e4ferenzen). Weitere Informationen zur Verwaltung Ihrer Marketingpr\u00e4ferenzen finden Sie im Abschnitt &#8222;<a href=\"#Your data protection rights\">Ihre Datenschutzrechte<\/a>&#8220;\u00a0 in dieser Mitteilung.<\/li>\n<li>Zur Einhaltung und Umsetzung geltender gesetzlicher Bestimmungen, Vereinbarungen und Richtlinien.<\/li>\n<li>um Verbindlichkeiten, verbotenem Verhalten und kriminellen Aktivit\u00e4ten vorzubeugen, sie zu erkennen und zu identifizieren, auf sie zu reagieren oder uns gegen sie zu verteidigen.<\/li>\n<li>F\u00fcr andere gesch\u00e4ftliche Zwecke, wie z. B. die Datenanalyse, die Identifizierung von Nutzungstrends, die Messung der Effektivit\u00e4t unseres Marketings und die Erweiterung, Anpassung und Verbesserung unserer Websites, Produkte und Dienstleistungen.<\/li>\n<\/ul>\n<p><strong>Informationen, die wir automatisch sammeln:<\/strong> Wenn Sie unsere Websites nutzen oder mit unserer Online-Werbung oder unseren Marketing-E-Mails interagieren ( im Zusammenhang mit unseren Websites, die &#8222;Online-Angebote&#8220;), erfassen wir automatisch bestimmte Informationen \u00fcber Ihr Ger\u00e4t. In einigen L\u00e4ndern, einschlie\u00dflich der L\u00e4nder des Europ\u00e4ischen Wirtschaftsraums (EWR), k\u00f6nnen diese Informationen nach den geltenden Datenschutzgesetzen als personenbezogene Daten gelten. Einige dieser Informationen k\u00f6nnen mithilfe von Cookies und \u00e4hnlichen Tracking-Technologien erfasst werden, wie unter der \u00dcberschrift \u201c<a href=\"#Cookies and similar tracking technology\">Cookies und \u00e4hnliche Tracking-Technologien<\/a>\u201d n\u00e4her erl\u00e4utert wird.<\/p>\n<p>Die von uns automatisch erfassten Daten k\u00f6nnen Informationen wie Ihre IP-Adresse, den Ger\u00e4tetyp, eindeutige Ger\u00e4teidentifikationsnummern, den Browsertyp, den ungef\u00e4hren geografischen Standort (z. B. Land oder Stadt) und andere technische Informationen umfassen. \u00a0Wir k\u00f6nnen zudem Informationen \u00fcber die Art und Weise erfassen, wie Ihr Ger\u00e4t mit unseren Online-Angeboten interagiert, einschlie\u00dflich der aufgerufenen Seiten und angeklickten Links.<\/p>\n<p><u>Wie wir diese Informationen verwenden:<\/u> Die Erfassung dieser Informationen erm\u00f6glicht es uns, die Personen, die unsere Online-Angebote nutzen und mit ihnen interagieren, besser zu verstehen, woher sie stammen und welche Inhalte auf unseren Online-Angeboten f\u00fcr sie von Interesse sind. Wir verwenden diese Informationen f\u00fcr unsere internen Analysezwecke und um die Qualit\u00e4t und Relevanz unserer Online-Angebote zu verbessern.<\/p>\n<p><strong>Informationen, die wir aus Drittquellen erhalten<\/strong>: erhalten, aber nur, wenn wir \u00fcberpr\u00fcft haben, dass diese Dritten entweder Ihre Zustimmung eingeholt haben oder anderweitig gesetzlich befugt oder verpflichtet sind, Ihre personenbezogenen Daten an uns weiterzugeben. Zu den Informationen, die wir von Dritten sammeln, geh\u00f6ren Kontaktinformationen und Berufsbezeichnungen. \u00a0Wir verwenden die Informationen, die wir von diesen Dritten erhalten, um die Richtigkeit der von uns \u00fcber Sie gespeicherten Daten zu gew\u00e4hrleisten und zu optimieren.<\/p>\n<p><strong>Widgets f\u00fcr soziale Medien:<\/strong> Unsere Website enth\u00e4lt Plugins von Social-Media-Plattformen wie facebook.com von Facebook Inc., 1601 S. California Ave, Palo Alto, CA 94304, USA; Twitter.com von Twitter Inc., 795 Folsom St., Suite 600, San Francisco CA 94107, USA; und google+ von Google Inc., 1600 Amphitheatre Parkway Mountain View, California, 94043, USA. Social-Media-Funktionen und -Widgets werden entweder von einem Drittanbieter oder direkt auf unseren Websites gehostet. Sie erkennen die Plugins in der Regel an dem Logo des jeweiligen Netzwerks, z.B. in Kombination mit dem Piktogramm einer geballten Hand mit erhobenem Daumen oder dem Zusatz &#8222;Empfehlung&#8220;, &#8222;Gef\u00e4llt mir&#8220; oder &#8222;Kommentar&#8220;. Einzelheiten zu Zweck und Umfang der Datenerhebung sowie der Verarbeitung und Nutzung der Daten durch die sozialen Netzwerke k\u00f6nnen Sie den Datenschutzrichtlinien von Facebook, Twitter und Google entnehmen.<\/p>\n<h3><a id=\"Who do we share your personal information with?\" name=\"Who do we share your personal information with?\"><\/a>An wen geben wir Ihre personenbezogenen Daten weiter?<\/h3>\n<p>Wir k\u00f6nnen Ihre personenbezogenen Daten an die folgenden Empf\u00e4ngerkategorien weitergeben:<\/p>\n<ul>\n<li><strong>unsere Konzerngesellschaften, Drittdienstleister und Partner,<\/strong> die uns Datenverarbeitungsdienste zur Verf\u00fcgung stellen (z. B. zur Unterst\u00fctzung der Bereitstellung unserer Online-Angebote, zur Bereitstellung von Funktionen oder zur Verbesserung der Sicherheit unserer Online-Angebote) oder die anderweitig personenbezogene Daten f\u00fcr Zwecke verarbeiten, die in dieser Datenschutzerkl\u00e4rung beschrieben oder Ihnen bei der Erfassung Ihrer personenbezogenen Daten mitgeteilt werden.<\/li>\n<li><strong>zust\u00e4ndige Strafverfolgungsbeh\u00f6rden, Aufsichtsbeh\u00f6rden, Regierungsstellen, Gerichte oder andere Dritte, <\/strong>wenn wir der Meinung sind, dass die Offenlegung notwendig ist, (i) um geltende Gesetze oder Vorschriften einzuhalten, (ii) um unsere gesetzlichen Rechte auszu\u00fcben, zu begr\u00fcnden oder zu verteidigen, oder (iii) um Ihre grundlegenden Interessen oder die Interessen einer anderen Person zu sch\u00fctzen;<\/li>\n<li><strong>einen potenziellen K\u00e4ufer<\/strong> (und seine Vertreter und Berater) in Verbindung mit einem geplanten Kauf, einer Fusion oder \u00dcbernahme eines Teils unseres Unternehmens, vorausgesetzt, wir informieren den K\u00e4ufer, dass er Ihre personenbezogenen Daten nur f\u00fcr die in dieser Datenschutzerkl\u00e4rung genannten Zwecke verwenden darf;<\/li>\n<li><strong>unsere Marketingpartner,<\/strong> um in unserem Namen E-Mails zu versenden, und\/oder f\u00fcr co-branded und\/oder co-sponsored Marketing- und Werbeveranstaltungen (wie z.B. Konferenzen), die in Verbindung mit einem anderen Unternehmen oder anderen Unternehmen angeboten werden. Wenn Sie sich f\u00fcr solche Marketing- und Werbeveranstaltungen anmelden oder daran teilnehmen, k\u00f6nnen wir und die jeweiligen Partnerunternehmen Informationen erhalten, die im Zusammenhang mit den gemeinsam gebrandeten und\/oder gesponserten Marketing- und Werbeveranstaltungen gesammelt wurden. F\u00fcr die Verwendung Ihrer pers\u00f6nlichen Daten gilt unser Datenschutzhinweis. Wir haben keine Kontrolle \u00fcber die Datenschutzpraktiken anderer Unternehmen, lesen Sie daher bitte deren Datenschutzbestimmungen.<\/li>\n<li>eine andere <strong>Person mit Ihrer Zustimmung<\/strong> zur Weitergabe.<\/li>\n<\/ul>\n<h3><a id=\"Cookies and similar tracking technology\" name=\"Cookies and similar tracking technology\"><\/a>Cookies und verwandte Tracking-Technologien<\/h3>\n<p>Wir verwenden Cookies und verwandte Tracking-Technologien (zusammenfassend &#8222;<strong>Cookies<\/strong>&#8222;), um personenbezogene Daten \u00fcber Sie zu sammeln und zu verwenden, auch um interessenbezogene Werbung zu schalten. Weitere Informationen \u00fcber die Arten von Cookies, die wir verwenden, warum und wie Sie Cookies verwalten k\u00f6nnen<br \/>\nfinden Sie in unserem <a href=\"\/en\/about\/cookie-policy\">Cookie-Hinweis<\/a>.<\/p>\n<h4>Wie sch\u00fctzen wir Ihre pers\u00f6nlichen Daten?<\/h4>\n<p>Wir nutzen geeignete administrative, organisatorische, technische sowie physische Sicherheitsvorkehrungen, um die von uns erfassten und verarbeiteten personenbezogenen Daten \u00fcber Sie zu sch\u00fctzen. Die von uns angewandten Ma\u00dfnahmen sind so konzipiert, dass sie ein dem Risiko der Verarbeitung Ihrer personenbezogenen Daten angemessenes Sicherheitsniveau gew\u00e4hrleisten und dazu beitragen, dass Ihre Daten sicher sind und nur Ihnen und denjenigen zur Verf\u00fcgung stehen, denen Sie den Zugriff gestattet haben (z. B. Ihren Nutzern).<\/p>\n<p>Es kann allerdings nicht garantiert werden, dass elektronische \u00dcbertragungen \u00fcber das Internet oder Informationsspeichertechnologien zu 100 % sicher sind, daher sollten Sie sorgf\u00e4ltig entscheiden, welche Informationen Sie uns auf diese Weise \u00fcbermitteln.<\/p>\n<h4>Links zu anderen Websites<\/h4>\n<p>Unsere Website kann Links zu anderen Websites enthalten, die nicht zu BloomReach geh\u00f6ren oder von BloomReach kontrolliert werden. Bitte beachten Sie, dass BloomReach nicht f\u00fcr die Datenschutzpraktiken dieser Websites verantwortlich ist. Wir empfehlen Ihnen, die Datenschutzrichtlinien und -erkl\u00e4rungen dieser Websites zu pr\u00fcfen, um sich \u00fcber deren Informationspraktiken zu informieren. Dieser Datenschutzhinweis gilt nur f\u00fcr Informationen, die \u00fcber unsere Websites gesammelt werden.<\/p>\n<h3><a id=\"Legal basis for processing personal information (EEA residents only)\" name=\"Legal basis for processing personal information (EEA residents only)\"><\/a>Rechtsgrundlage f\u00fcr die Verarbeitung personenbezogener Daten (nur f\u00fcr Einwohner des EWR)<\/h3>\n<p>Wenn Sie Ihren Wohnsitz im Europ\u00e4ischen Wirtschaftsraum haben oder ein Besucher aus dem Europ\u00e4ischen Wirtschaftsraum sind, h\u00e4ngt unsere Rechtsgrundlage f\u00fcr die Erhebung und Verwendung der oben beschriebenen personenbezogenen Daten von den betreffenden personenbezogenen Daten und dem spezifischen Kontext ab, in dem wir sie erheben. In den meisten F\u00e4llen verwenden wir personenbezogene Daten, wenn wir Ihre Zustimmung dazu haben oder wenn die Verarbeitung in unserem legitimen Gesch\u00e4ftsinteresse liegt. Zu unseren berechtigten Interessen geh\u00f6ren in der Regel: (i) Verbesserung unserer Online-Angebots, Produkten und Dienstleistungen; (ii) f\u00fcr unsere Marketingaktivit\u00e4ten; und (iii) zur Messung der Effektivit\u00e4t unserer Marketing- und Werbekampagnen.<\/p>\n<p>In einigen F\u00e4llen sind wir gesetzlich dazu verpflichtet, personenbezogene Daten von Ihnen zu erheben. Wenn wir Sie auffordern, personenbezogene Daten zur Verf\u00fcgung zu stellen, um einer gesetzlichen Verpflichtung nachzukommen oder einen Vertrag mit Ihnen zu schlie\u00dfen, werden wir dies zum entsprechenden Zeitpunkt mitteilen und Sie dar\u00fcber informieren, ob die Bereitstellung der Daten obligatorisch ist oder nicht (sowie \u00fcber die m\u00f6glichen Folgen, wenn Sie Ihre personenbezogenen Daten nicht bereitstellen).<\/p>\n<p>Wenn Sie Fragen zu den Rechtsgrundlagen haben, nach denen wir Ihre personenbezogenen Daten erheben und verwenden, oder weitere Informationen ben\u00f6tigen, wenden Sie sich bitte an uns, indem Sie die unter der \u00dcberschrift \u201c<a href=\"#Contact Us\">Kontakt aufnehmen<\/a>\u201d angegebenen Kontaktm\u00f6glichkeiten nutzen.<\/p>\n<h3><a id=\"International data transfers\" name=\"International data transfers\"><\/a>Internationale Daten\u00fcbermittlung<\/h3>\n<p>Wir sind ein wachsendes Unternehmen mit Niederlassungen in diversen L\u00e4ndern, unter anderem in den Vereinigten Staaten, Gro\u00dfbritannien, Indien, Deutschland und den Niederlanden. Obwohl sich unsere wichtigsten Datenzentren in den USA, Irland und den Niederlanden befinden, k\u00f6nnen wir personenbezogene Daten oder andere Informationen an Bloomreach-B\u00fcros au\u00dferhalb der USA oder der Europ\u00e4ischen Union \u00fcbermitteln. Dar\u00fcber hinaus k\u00f6nnen wir andere Unternehmen und Personen damit beauftragen, Funktionen in unserem Namen auszuf\u00fchren.<\/p>\n<p>In diesen L\u00e4ndern gelten m\u00f6glicherweise andere Datenschutzgesetze als in Ihrem Land. Wir haben jedoch angemessene Sicherheitsvorkehrungen getroffen, um zu gew\u00e4hrleisten, dass Ihre personenbezogenen Daten in \u00dcbereinstimmung mit diesen Datenschutzbestimmungen gesch\u00fctzt werden. Zu diesen Sicherheitsvorkehrungen geh\u00f6rt die Umsetzung der Standardvertragsklauseln der Europ\u00e4ischen Kommission f\u00fcr die \u00dcbermittlung personenbezogener Daten zwischen unseren Konzernunternehmen, die alle Konzernunternehmen verpflichten, personenbezogene Daten, die sie aus dem EWR verarbeiten, gem\u00e4\u00df dem europ\u00e4ischen Datenschutzrecht zu sch\u00fctzen. Unsere Standardvertragsklauseln k\u00f6nnen auf Anfrage zur Verf\u00fcgung gestellt werden.Wir haben \u00e4hnliche angemessene Schutzma\u00dfnahmen bei unseren externen Dienstleistern und Partnern implementiert. Weitere Einzelheiten k\u00f6nnen auf Anfrage zur Verf\u00fcgung gestellt werden, um personenbezogene Daten, die sie aus dem EWR verarbeiten, in \u00dcbereinstimmung mit dem Datenschutzrecht der Europ\u00e4ischen Union zu sch\u00fctzen.<\/p>\n<h3><a id=\"Data Retention\" name=\"Data Retention\"><\/a>Datenaufbewahrung<\/h3>\n<p>Wir speichern personenbezogene Daten, die wir \u00fcber Sie erheben, wenn wir ein laufendes legitimes Gesch\u00e4ftsinteresse daran haben (z. B. um Ihnen eine von Ihnen angeforderte Dienstleistung zu erbringen oder um geltende gesetzliche, steuerliche oder buchhalterische Auflagen zu erf\u00fcllen, um unsere Vereinbarungen durchzusetzen oder unseren rechtlichen Verpflichtungen nachzukommen).<\/p>\n<p>Wenn wir keine weitere legitime gesch\u00e4ftliche Veranlassung haben, Ihre personenbezogenen Daten zu verarbeiten, werden wir sie entweder l\u00f6schen oder anonymisieren, oder, falls dies nicht m\u00f6glich ist (z. B. weil Ihre personenbezogenen Daten in Sicherungsarchiven gespeichert wurden), werden wir Ihre personenbezogenen Daten sicher aufbewahren und von jeder weiteren Verarbeitung ausschlie\u00dfen, bis die L\u00f6schung m\u00f6glich ist.<\/p>\n<p><a href=\"#Contact Us\">Wenden Sie sich bitte an uns<\/a>, wenn Sie Fragen zu den von uns erfassten Daten und\/oder zur Verwendung der von uns erfassten Daten haben.<\/p>\n<h3><a id=\"Your data protection rights\" name=\"Your data protection rights\"><\/a>Ihre Datenschutzrechte<\/h3>\n<p>Sie haben die folgenden Datenschutzrechte:<\/p>\n<ul>\n<li>Sie k\u00f6nnen <strong>jederzeit auf Ihre pers\u00f6nlichen Daten zugreifen, sie \u00fcberpr\u00fcfen, \u00e4ndern, aktualisieren oder l\u00f6schen<\/strong> indem Sie sich mit uns \u00fcber <a href=\"mailto:privacy@bloomreach.com\">privacy@bloomreach.com<\/a> in Verbindung setzen. \u00a0Bitte beachten Sie, dass wir f\u00fcr den Zugriff auf Ihre personenbezogenen Daten und deren Weitergabe eine geringe Geb\u00fchr erheben k\u00f6nnen, sofern dies nach geltendem Recht zul\u00e4ssig ist. Die Aktualisierung oder Entfernung Ihrer personenbezogenen Daten ist f\u00fcr Sie kostenlos.<\/li>\n<li>Wenn Sie Ihre pers\u00f6nlichen Daten aus einem Erfahrungsbericht auf der Website entfernen oder die Entfernung Ihrer pers\u00f6nlichen Daten aus unserem Blog oder dem Community-Forum beantragen wollen, kontaktieren Sie uns unter <a href=\"mailto:privacy@bloomreach.com\">privacy@bloomreach.com<\/a>. In einigen F\u00e4llen kann es sein, dass wir nicht in der Lage sind, Ihre personenbezogenen Daten zu entfernen; in diesem Fall werden wir Sie dar\u00fcber informieren, wenn und warum es uns nicht m\u00f6glich ist.<\/li>\n<li>Wenn Sie Ihren Wohnsitz im Europ\u00e4ischen Wirtschaftsraum haben, k\u00f6nnen Sie <strong>au\u00dferdem der Verarbeitung Ihrer<\/strong> personenbezogenen Daten widersprechen, uns auffordern <strong>die Verarbeitung Ihrer<\/strong> personenbezogenen Daten einzuschr\u00e4nken oder <strong>die \u00dcbertragbarkeit Ihrer<\/strong><br \/>\npersonenbezogenen Daten beantragen. Um diese Rechte auszu\u00fcben, schicken Sie eine E-Mail an <a href=\"mailto:privacy@bloomreach.com\">privacy@bloomreach.com<\/a>.<\/li>\n<li>Sie k\u00f6nnen <strong>den Empfang von Werbe-E-Mails oder Textnachrichten<\/strong> von uns widerrufen, indem Sie auf den Link &#8222;Abbestellen&#8220; in der E-Mail klicken oder die Website <a href=\"https:\/\/www.bloomreach.com\/en\/legal\/control-your-data\/opt-out\">https:\/\/www.bloomreach.com\/en\/legal\/control-your-data\/opt-out<\/a><br \/>\n. \u00a0Wenn Sie sich daf\u00fcr entscheiden, keine Marketing-Informationen mehr zu erhalten, k\u00f6nnen wir weiterhin mit Ihnen kommunizieren, z. B. \u00fcber Ihre Sicherheits-Updates, Produktfunktionen, Antworten auf Service-Anfragen oder andere transaktionsbezogene, nicht-marketing\/administrative Zwecke.<\/li>\n<li>Wenn wir Ihre personenbezogenen Daten mit Ihrer Zustimmung erfasst und verarbeitet haben, k\u00f6nnen Sie Ihre <strong>Zustimmung jederzeit <\/strong>widerrufen. Der Widerruf Ihrer Einwilligung ber\u00fchrt weder die Rechtm\u00e4\u00dfigkeit der von uns vor Ihrem Widerruf durchgef\u00fchrten Verarbeitung noch die Verarbeitung Ihrer personenbezogenen Daten, die auf der Grundlage anderer rechtm\u00e4\u00dfiger Verarbeitungsgr\u00fcnde als der Einwilligung erfolgt.<\/li>\n<li>Sie haben <strong>das Recht, sich bei einer Datenschutzbeh\u00f6rde<\/strong> \u00fcber die Erfassung und Verwendung Ihrer personenbezogenen Daten durch uns zu beschweren. \u00a0F\u00fcr weitere Informationen wenden Sie sich bitte an Ihre \u00f6rtliche Datenschutzbeh\u00f6rde. Die Kontaktdaten der Datenschutzbeh\u00f6rden im Europ\u00e4ischen Wirtschaftsraum (&#8222;EWR&#8220;) finden <a href=\"http:\/\/ec.europa.eu\/justice\/data-protection\/article-29\/structure\/data-protection-authorities\/index_en.htm\" target=\"_blank\" rel=\"noopener\">Sie hier<\/a>.<\/li>\n<\/ul>\n<p>Wir beantworten alle Anfragen, die wir von Personen erhalten, die ihre Datenschutzrechte in \u00dcbereinstimmung mit den geltenden Datenschutzgesetzen wahrnehmen m\u00f6chten. Zum Schutz Ihrer Privatsph\u00e4re und Ihrer Sicherheit unternehmen wir die erforderlichen Schritte, um Ihre Identit\u00e4t zu \u00fcberpr\u00fcfen, bevor wir Ihnen Zugang zu Ihrem Konto gew\u00e4hren oder Korrekturen an Ihren pers\u00f6nlichen Daten vornehmen.<\/p>\n<h3><a id=\"Children\" name=\"Children\"><\/a>Kinder<\/h3>\n<p>Wir erf\u00fcllen die Anforderungen des COPPA (Children&#8217;s Online Privacy Protection Act), da wir keine Informationen von Personen unter 13 Jahren sammeln. Die Website und ihr Inhalt richten sich an Personen, die mindestens 18 Jahre alt sind. Wir sammeln keine Informationen von Personen unter 18 Jahren. Wenn Sie unter 18 Jahre alt sind, ist es Ihnen nicht gestattet, diese Website zu nutzen, es sei denn, Sie haben die Zustimmung eines Elternteils oder Erziehungsberechtigten und werden von diesem beaufsichtigt.<\/p>\n<h3><a id=\"Changes to our Privacy Notice\" name=\"Changes to our Privacy Notice\"><\/a>\u00c4nderungen unserer Datenschutzrichtlinien<\/h3>\n<p>Wir sind berechtigt, diese Datenschutzrichtlinie von Zeit zu Zeit zu \u00fcberarbeiten, um sie an ver\u00e4nderte rechtliche, technische oder gesch\u00e4ftliche Entwicklungen anzupassen. Die jeweils aktuelle Version dieser Datenschutzrichtlinie gilt f\u00fcr die Verwendung Ihrer pers\u00f6nlichen Daten. Wenn wir unsere Datenschutzrichtlinie aktualisieren, werden wir die entsprechenden Ma\u00dfnahmen ergreifen, um Sie entsprechend der Tragweite der von uns vorgenommenen \u00c4nderungen zu informieren. Wir werden Ihre Zustimmung zu wesentlichen \u00c4nderungen der Datenschutzrichtlinie einholen, wenn und soweit dies nach geltendem Datenschutzrecht erforderlich ist. Wann diese Datenschutzrichtlinie zuletzt aktualisiert wurde, entnehmen Sie dem Datum der letzten \u00dcberarbeitung, das oben in dieser Datenschutzrichtlinie angezeigt wird.<\/p>\n<h4><a id=\"Contact Us\" name=\"Contact Us\"><\/a>Kontaktieren Sie uns<\/h4>\n<p>Wenn Sie Fragen haben, Kommentare oder Bedenken zu BloomReach oder dieser Datenschutzrichtlinie \u00e4u\u00dfern m\u00f6chten, kontaktieren Sie bitte unseren Datenschutzbeauftragten per E-Mail <a href=\"mailto:privacy@bloomreach.com\">privacy@bloomreach.com<\/a><br \/>\noder \u00fcber die unten angegebenen Kontaktdaten.<\/p>\n<p>Z. Hd.: Datenschutzbeauftragter<\/p>\n<p>Postanschrift:<\/p>\n<p>BloomReach, Inc.<\/p>\n<p>82 Pioneer Way<\/p>\n<p>Mountain View, CA 94041<\/p>\n<p>Wenn Sie im EWR ans\u00e4ssig sind:<\/p>\n<p>BloomReach, B.V.<\/p>\n<p>Keizersgracht 125-127, 1015 CJ<\/p>\n<p>1076 EE, Amsterdam<br \/>\nNiederlande<br \/>\nZ. Hd.: Datenschutzbeauftragter<\/p>\n<p>Sie k\u00f6nnen uns per E-Mail an <a href=\"mailto:privacy@bloomreach.com\">privacy@bloomreach.com<\/a>\u00a0oder telefonisch unter +1 (888) 263-3917 erreichen.<\/p>\n<p>Wenn Sie Ihren Wohnsitz im EWR haben, ist BloomReach B.V. gemeinsam mit BloomReach, Inc. der f\u00fcr die Verarbeitung Ihrer pers\u00f6nlichen Daten Verantwortliche.<\/p>\n<p>Wenn Sie ein Konsument sind, ist unser Kunde, dessen digitale Angebote Sie nutzen, der f\u00fcr die Verarbeitung Ihrer personenbezogenen Daten Verantwortliche.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n","protected":false},"parent":0,"menu_order":0,"template":"","class_list":["post-2260","legal","type-legal","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.bloomreach.com\/de\/wp-json\/wp\/v2\/legal\/2260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bloomreach.com\/de\/wp-json\/wp\/v2\/legal"}],"about":[{"href":"https:\/\/www.bloomreach.com\/de\/wp-json\/wp\/v2\/types\/legal"}],"version-history":[{"count":1,"href":"https:\/\/www.bloomreach.com\/de\/wp-json\/wp\/v2\/legal\/2260\/revisions"}],"predecessor-version":[{"id":57272,"href":"https:\/\/www.bloomreach.com\/de\/wp-json\/wp\/v2\/legal\/2260\/revisions\/57272"}],"wp:attachment":[{"href":"https:\/\/www.bloomreach.com\/de\/wp-json\/wp\/v2\/media?parent=2260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}