{"id":2250,"date":"2024-05-09T13:58:32","date_gmt":"2024-05-09T13:58:32","guid":{"rendered":"https:\/\/www.bloomreach.com\/legal\/privacy-policy-2"},"modified":"2024-09-12T12:51:07","modified_gmt":"2024-09-12T12:51:07","slug":"privacy-policy","status":"publish","type":"legal","link":"https:\/\/www.bloomreach.com\/de\/legal\/privacy-policy","title":{"rendered":"Datenschutz bei Bloomreach"},"content":{"rendered":"<section>\n<div class=\"container\">\n<div class=\"row\">\n<div class=\"col-lg-12\">\n<h2 class=\"h1\">ALLGEMEINE DATENSCHUTZGRUNDS\u00c4TZE VON BLOOMREACH<\/h2>\n<div>\n<h3>Leitwerte zum Datenschutz bei Bloomreach<\/h3>\n<p>Die Privatsph\u00e4re von Personen, deren personenbezogene Daten wir verarbeiten, sei es im Auftrag anderer (wie etwa unserer Kunden und deren Endbenutzer) oder innerhalb von BloomReach, ist BloomReach \u00e4u\u00dferst wichtig.<\/p>\n<p>Nachfolgend sind die Datenschutzgrunds\u00e4tze (\u201c<strong>Grunds\u00e4tze<\/strong>\u201d) aufgef\u00fchrt, die wir weltweit anwenden, wann immer wir personenbezogene Daten in unseren Produkten und Dienstleistungen sowie in der gesamten BloomReach-Unternehmensgruppe erfassen, verwenden oder verwalten.<\/p>\n<p>Der Zweck dieser Grunds\u00e4tze besteht darin, Mindeststandards daf\u00fcr festzulegen, wie wir personenbezogene Daten zu verarbeiten haben, um zu garantieren, dass wir in der gesamten Organisation einheitlich und in \u00dcbereinstimmung mit geltendem Recht arbeiten.<\/p>\n<p>TDie Grunds\u00e4tze gelten f\u00fcr alle Mitarbeiter von BloomReach und sind der Ma\u00dfstab daf\u00fcr, wie wir unsere Produkte und Dienstleistungen entwickeln, von uns erfasste Daten verwalten, unsere Partner ausw\u00e4hlen und mit diesen interagieren und unseren Umgang mit der \u00d6ffentlichkeit gestalten. &nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h3>GRUNDS\u00c4TZE<\/h3>\n<h4>1. TRANSPARENZ: Wir m\u00fcssen offen und ehrlich mit der Frage umgehen, welche Daten wir verarbeiten.<\/h4>\n<p>Wir m\u00fcssen gegen\u00fcber Personen und anderen Parteien, von denen wir personenbezogene Daten erfassen, stets transparent sein. Dies bedeutet, dass wir diesen Rechtssubjekten genaue, transparente und einfach zug\u00e4ngliche Informationen dar\u00fcber zur Verf\u00fcgung stellen m\u00fcssen, wie und warum wir ihre personenbezogenen Daten verwenden und weitergeben, sowie alle weiteren Informationen, die ben\u00f6tigt werden, um eine angemessene und geltendem Recht entsprechende Nutzung zu gew\u00e4hrleisten. Die von uns bereitgestellten Informationen m\u00fcssen ausreichen, damit sie eine fundierte Entscheidung \u00fcber die Nutzung ihrer personenbezogenen Daten treffen k\u00f6nnen.<\/p>\n<p>Wenn wir Informationen direkt von Einzelpersonen sammeln, m\u00fcssen wir diese davon in Kenntnis setzen, sobald personenbezogene Daten gesammelt werden (oder so bald wie m\u00f6glich danach). Wenn wir personenbezogene Daten nicht unmittelbar beim betroffenen Rechtssubjekt, sondern bei Dritten sammeln (z. B. bei LinkedIn oder anderen \u00f6ffentlich zug\u00e4nglichen Quellen), m\u00fcssen wir das Rechtssubjekt so schnell wie m\u00f6glich informieren, es sei denn, dies ist unm\u00f6glich oder mit unverh\u00e4ltnism\u00e4\u00dfigem Aufwand verbunden.<\/p>\n<p>&nbsp;<\/p>\n<h4>2. LEGITIME GESCH\u00c4FTLICHE ZWECKE: Wir d\u00fcrfen personenbezogene Daten nur f\u00fcr festgelegte, angemessene und rechtm\u00e4\u00dfige Zwecke verwenden<\/h4>\n<p>Wir d\u00fcrfen personenbezogene Daten nur verarbeiten, wenn wir nachweisen k\u00f6nnen, dass wir eine Rechtsgrundlage f\u00fcr die Verwendung der Daten haben, und m\u00fcssen diese Daten in rechtm\u00e4\u00dfiger und angemessener Weise verarbeiten.<\/p>\n<p>Soweit m\u00f6glich, sollten wir uns auf Gr\u00fcnde berufen, die nicht auf einer Einwilligung beruhen (wie etwa unsere berechtigten Interessen oder die Erf\u00fcllung unserer vertraglichen Verpflichtungen) und vermeiden, uns auf die Einwilligung zur Verarbeitung personenbezogener Daten zu verlassen, sofern dies nicht gesetzlich vorgeschrieben ist.<\/p>\n<p>Wir d\u00fcrfen personenbezogene Daten nur in einer Weise erfassen und verwenden, die mit den diesbez\u00fcglichen Hinweisen \u00fcbereinstimmt, die den Betroffenen zum Zeitpunkt der Erfassung bereitgestellt werden.<\/p>\n<p>Wir d\u00fcrfen die personenbezogenen Daten einer Person nur an Dritte weitergeben, wenn wir \u00fcber die erforderlichen Genehmigungen verf\u00fcgen oder es einen stichhaltigen gesch\u00e4ftlichen Grund gibt, die personenbezogenen Daten weiterzugeben.<\/p>\n<p>&nbsp;<\/p>\n<h4>3. INDIVIDUELLE AUSWAHL UND KONTROLLE: In bestimmten Situationen m\u00fcssen wir eine individuelle Zustimmung zur Verarbeitung personenbezogener Daten einholen und es Einzelpersonen erm\u00f6glichen, die Verarbeitung ihrer personenbezogenen Daten zu kontrollieren.<\/h4>\n<p>In bestimmten Situationen m\u00fcssen wir m\u00f6glicherweise die Zustimmung einer Person einholen, ehe wir ihre personenbezogenen Daten verarbeiten. Zum Beispiel verlangt das Gesetz, dass wir die Zustimmung von Personen zur Erhebung, Verwendung oder Offenlegung \u201esensibler\u201c personenbezogener Daten wie etwa Gesundheits- und Finanzdaten, genetischer Daten, Geolokalisierungsdaten oder biometrischer Daten zur eindeutigen Identifizierung oder personenbezogener Daten, aus denen die rassische oder ethnische Herkunft, politische Meinungen, religi\u00f6se oder philosophische \u00dcberzeugungen oder die Mitgliedschaft in einer Gewerkschaft oder die sexuelle Orientierung hervorgehen, einholen. &nbsp;&nbsp;<\/p>\n<p>Wenn wir desweiteren beabsichtigen, personenbezogene Daten in anderer Weise als zum Zeitpunkt der Erfassung beschrieben oder anders als gesetzlich vorgeschrieben zu verwenden oder offenzulegen, m\u00fcssen wir m\u00f6glicherweise ebenso die vorherige Zustimmung einer Person einholen.<\/p>\n<p>Wenn wir die Einwilligung einer Person einholen, m\u00fcssen wir dar\u00fcber Protokoll f\u00fchren, um nachzuweisen, wozu die Person eingewilligt hat, was ihr mitgeteilt wurde sowie wann und wie sie eingewilligt hat.<\/p>\n<p>Datenschutzgrunds\u00e4tze sind dar\u00fcber hinaus Dokumente, die Einzelpersonen die Kontrolle dar\u00fcber geben, welche personenbezogenen Daten Organisationen von ihnen sammeln und wie diese Daten verwendet werden. In bestimmten Situationen m\u00f6chten wir Einzelpersonen m\u00f6glicherweise das Recht einr\u00e4umen, bestimmten Funktionen, welche die Erfassung personenbezogener Daten beinhalten, zuzustimmen oder diese abzulehnen.<\/p>\n<p>Wir d\u00fcrfen Direktmarketing-Nachrichten nur in \u00dcbereinstimmung mit ihren Marketingpr\u00e4ferenzen und dem rechtlichen Rahmen f\u00fcr Direktmarketing an Einzelpersonen senden. Wir m\u00fcssen Einzelpersonen auch die M\u00f6glichkeit geben, sich jederzeit von unserem Direktmarketing abzumelden.<\/p>\n<p>&nbsp;<\/p>\n<h4>4. DATENSPARSAMKEIT: Wir d\u00fcrfen nur notwendige und relevante personenbezogene Daten erheben.<\/h4>\n<p>Wir d\u00fcrfen personenbezogene Daten nur f\u00fcr rechtm\u00e4\u00dfige geschaftliche Zwecke erheben und wir d\u00fcrfen nur so viele personenbezogene Daten erheben, wie f\u00fcr diesen Zweck erforderlich und relevant sind. Wir m\u00fcssen daf\u00fcr Sorge tragen, dass unsere Produkte, Dienstleistungen und Gesch\u00e4ftsprozesse darauf ausgelegt sind, so wenige personenbezogene Daten wie m\u00f6glich zu erfassen.<\/p>\n<p>&nbsp;<\/p>\n<h4>5. HAFTBARKEIT: Wir sind daf\u00fcr verantwortlich, wie wir und unsere Dienstleister personenbezogene Daten verarbeiten.<\/h4>\n<p>Wir m\u00fcssen die Verantwortung daf\u00fcr \u00fcbernehmen, wie wir personenbezogene Daten verarbeiten, ob diese personenbezogenen Daten direkt von uns erfasst werden oder ob wir sie im Auftrag unserer Kunden verarbeiten. Wir sind auch f\u00fcr die Verarbeitung personenbezogener Daten durch unsere Dienstleister oder andere Rechtssubjekte verantwortlich, die personenbezogene Daten in unserem Auftrag oder in unserem Namen verarbeiten.<\/p>\n<p>Wir m\u00fcssen Verfahren bereithalten, um unsere Rechtskonformit\u00e4t und Rechenschaftspflicht im Hinblick auf die Grunds\u00e4tzen des Umgangs mit personenbezogenen Daten nachzuweisen, sowie Nachweise dar\u00fcber, dass solche Verfahren \u00fcberwacht und bewertet und ggf. erforderliche Ma\u00dfnahmen oder \u00c4nderungen umgesetzt werden. Solche Verfahren sollten die F\u00fchrung bestimmter Aufzeichnungen \u00fcber alle personenbezogenen Daten umfassen, f\u00fcr die wir verantwortlich sind oder die wir im Auftrag unserer Kunden verarbeiten.<\/p>\n<p>&nbsp;<\/p>\n<h4>6. AUFBEWAHRUNG\/L\u00d6SCHUNG: Wir d\u00fcrfen personenbezogene Daten nicht l\u00e4nger als notwendig verwenden und aufbewahren.<\/h4>\n<p>Wir d\u00fcrfen personenbezogene Daten nur behalten, wenn wir dazu tats\u00e4chliche gesch\u00e4ftliche oder rechtliche Gr\u00fcnde haben; wir d\u00fcrfen diese Daten ausschlie\u00dflich f\u00fcr jene Zwecke behalten, die den Personen oder anderen Parteien, deren personenbezogene Daten wir verarbeiten, mitgeteilt wurden. Wir d\u00fcrfen personenbezogene Daten nicht unbegrenzt behalten. Sobald personenbezogene Daten f\u00fcr die Zwecke, f\u00fcr die sie erhoben wurden, nicht mehr erforderlich oder veraltet sind, sollten sie gel\u00f6scht oder sicher gel\u00f6scht werden, sofern gesetzlich nichts anderes vorgeschrieben ist. Es sollten alle angemessenen Schritte unternommen werden, um ungenaue Daten zu l\u00f6schen oder zu berichtigen. &nbsp;<\/p>\n<p>Wenn wir personenbezogene Daten im Auftrag unserer Kunden verarbeiten, werden diese Daten von uns nur so lange verwendet und gespeichert, wie unser Kunde es verlangt, es sei denn, dies ist gesetzlich vorgeschrieben oder notwendig, um eine bestehende Gesch\u00e4ftsbeziehung zu verwalten. &nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h4>7. GENAUIGKEIT: Wir m\u00fcssen daf\u00fcr Sorge tragen, dass personenbezogene Daten korrekt, vollst\u00e4ndig und aktuell sind.<\/h4>\n<p>Wir m\u00fcssen s\u00e4mtliche zweckm\u00e4\u00dfigen Ma\u00dfnahmen ergreifen, um zu garantieren, dass die von uns verarbeiteten personenbezogenen Daten korrekt, vollst\u00e4ndig und aktuell sind. Zu diesen Ma\u00dfnahmen geh\u00f6rt es, eine Quellen personenbezogener Daten, unabh\u00e4ngig davon, ob es sich um die betroffene Person oder ein anderes Rechtssubjekt handelt, regelm\u00e4\u00dfig aufzufordern, die Richtigkeit und Vollst\u00e4ndigkeit der personenbezogenen Daten in unseren Aufzeichnungen zu \u00fcberpr\u00fcfen; Sofern m\u00f6glich sind Self-Service-Tools bereitzustellen, mit denen Einzelpersonen ihre personenbezogenen Daten in unseren Aufzeichnungen aktualisieren k\u00f6nnen.<\/p>\n<p>&nbsp;<\/p>\n<h4>8. KUNDENHINWEISE: Wir m\u00fcssen uns an die Verarbeitungshinweise unserer Kunden halten.<\/h4>\n<p>Wenn wir personenbezogene Daten im Auftrag unserer Kunden erfassen, speichern und verwenden, d\u00fcrfen wir diese personenbezogenen Daten nur gem\u00e4\u00df Anweisung bzw. Genehmigung unserer Kunden verwenden und nicht f\u00fcr unsere eigenen Zwecke (oder die Zwecke Dritter). Wir m\u00fcssen die Vertraulichkeit und Sicherheit der personenbezogenen Daten unserer Kunden gem\u00e4\u00df unseren vertraglichen Verpflichtungen, die wir diesen gegen\u00fcber haben, jederzeit wahren. Wenn wir Fragen oder Anfragen in Bezug auf personenbezogene Daten erhalten, die wir im Auftrag unserer Kunden verwenden, m\u00fcssen wir den betreffenden Kunden informieren und bei der Beantwortung dieser Anfrage unterst\u00fctzen.<\/p>\n<p>&nbsp;<\/p>\n<h4>9. INDIVIDUELLE ZUGRIFFSRECHTE: Wir m\u00fcssen die Rechte und Entscheidungen von Einzelpersonen respektieren<\/h4>\n<p>Einzelpersonen haben bestimmte Rechte und Wahlm\u00f6glichkeiten in Bezug auf die Verwendung ihrer personenbezogenen Daten, einschlie\u00dflich des Rechts, zu verlangen, dass wir bestimmte Informationen \u00fcber ihre von uns gespeicherten personenbezogenen Daten best\u00e4tigen. Sie k\u00f6nnen uns auch bitten, ungenaue personenbezogene Daten, die wir gespeichert haben, zu korrigieren oder ihre personenbezogenen Daten zu l\u00f6schen.<\/p>\n<p>In einigen Regionen (wie dem Europ\u00e4ischen Wirtschaftsraum) haben Einzelpersonen das Recht, eine Kopie aller \u00fcber sie gespeicherten personenbezogenen Daten zu erhalten. Unter bestimmten, genau abgegrenzten Umst\u00e4nden k\u00f6nnen sie auch berechtigt sein, zu verlangen, dass wir ihre Daten an andere Dritte \u00fcbermitteln.<\/p>\n<p>Auf Fragen, Beschwerden und Anfragen von Personen oder Dritten, von denen wir personenbezogene Daten im Zusammenhang mit der Aus\u00fcbung dieser Rechte erheben, m\u00fcssen wir innerhalb einer angemessenen Frist und rechtskonform reagieren.<\/p>\n<p>Dar\u00fcber hinaus m\u00fcssen wir, sofern gesetzlich vorgeschrieben, Einzelpersonen erlauben, die Verwendung ihrer personenbezogenen Daten f\u00fcr Direktmarketingzwecke sowohl vor als auch nach der Erfassung dieser Daten abzulehnen. Wir m\u00fcssen von Einzelpersonen ge\u00e4u\u00dferte Marketingpr\u00e4ferenzen stets respektieren.<\/p>\n<p>Wenn wir personenbezogene Daten im Namen unserer Kunden verarbeiten, unterst\u00fctzen wir s\u00e4mtliche Kunden bei Bedarf dabei, der Anfrage einer Person nachzukommen, die ihre Rechte wahrnehmen m\u00f6chte.<\/p>\n<p>&nbsp;<\/p>\n<h4>10. SICHERHEITS- UND VERLETZUNGSMELDUNG: Wir m\u00fcssen angemessene Sicherheitsvorkehrungen treffen und sicherstellen, dass Sicherheitsverletzungen in geeigneter Weise gemeldet werden<\/h4>\n<p>Wir m\u00fcssen geeignete physische, technische und administrative Sicherheitsma\u00dfnahmen treffen, um die von uns verarbeiteten personenbezogenen Daten vor unbefugter oder rechtswidriger Verarbeitung oder Offenlegung sowie vor versehentlichem Verlust, Zerst\u00f6rung oder Besch\u00e4digung zu sch\u00fctzen.<\/p>\n<p>Wenn wir einen Drittanbieter beauftragen, f\u00fcr uns personenbezogene Daten zu sammeln, zu speichern oder zu verwenden, m\u00fcssen wir diesem strenge vertragliche Verpflichtungen hinsichtlich Datenschutz und -Sicherheit auferlegen. &nbsp;<\/p>\n<p>Wir m\u00fcssen daf\u00fcr Sorge tragen, dass Sicherheitsverletzungen, sofern dies gesetzlich vorgeschrieben ist, den zust\u00e4ndigen Aufsichtsbeh\u00f6rden und\/oder den betroffenen Personen gem\u00e4\u00df geltendem Recht innerhalb einer angemessenen Frist gemeldet werden. &nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h4>11. INTERNATIONALE DATENTRANSFERS: Wir m\u00fcssen bei internationalen \u00dcbertragungen personenbezogener Daten die Sicherheit dieser Daten gew\u00e4hrleisten<\/h4>\n<p>In einigen Regionen ist keine \u00dcbertragung personenbezogener Daten in andere Regionen zul\u00e4ssig, es sei denn, es besteht ein angemessenes Datenschutzniveau f\u00fcr die personenbezogenen Daten bei ihrem Empfang. &nbsp;<\/p>\n<p>Wir d\u00fcrfen personenbezogene Daten nicht international \u00fcbermitteln, es sei denn, wir haben zuvor geeignete Schritte unternommen, wie z. B. die von der Europ\u00e4ischen Kommission genehmigten Vertragsklauseln (die sogenannten \u201eMusterklauseln\u201c), um die \u00fcbermittelten personenbezogenen Daten zu sch\u00fctzen. &nbsp;&nbsp;&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h4>12. EINGEBAUTER DATENSCHUTZ (PRIVACY BY DESIGN): Wir m\u00fcssen durch geeignete Ma\u00dfnahmen gew\u00e4hrleisten, dass die Prinzipien von &#8222;Privacy by Design and Default&#8220; in unsere Prozesse und Systeme integriert sind<\/h4>\n<p>Wir m\u00fcssen interne Richtlinien einf\u00fchren und Ma\u00dfnahmen implementieren, welche die Grunds\u00e4tze &#8222;Privacy by Design and Default&#8220; befolgen und einbetten. &nbsp;<\/p>\n<p>Dies bedeutet, dass wir beim Entwerfen, Entwickeln und Betreiben von Produkten, Dienstleistungen und Gesch\u00e4ftsprozessen verstehen sollten, welche personenbezogenen Daten wie verarbeitet werden sollen und warum sie in der vorgesehenen Weise verarbeitet werden sollen; soweit m\u00f6glich, m\u00fcssen wir die Verarbeitung personenbezogener Daten minimieren und Informationen so schnell wie m\u00f6glich pseudonymisieren oder anonymisieren. Datenschutz-Folgenabsch\u00e4tzungen (PIAs) sollten, wo angemessen oder gesetzlich vorgeschrieben, in die Produkt\u00fcberpr\u00fcfung und die Onboarding-Prozesse f\u00fcr Lieferanten integriert werden.<\/p>\n<p>&nbsp;<\/p>\n<p><em>BloomReach Inc. und seine Tochtergesellschaften<\/em><\/p>\n<p>STAND: 18. MAI 2018<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/section>\n","protected":false},"parent":0,"menu_order":0,"template":"","class_list":["post-2250","legal","type-legal","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.bloomreach.com\/de\/wp-json\/wp\/v2\/legal\/2250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bloomreach.com\/de\/wp-json\/wp\/v2\/legal"}],"about":[{"href":"https:\/\/www.bloomreach.com\/de\/wp-json\/wp\/v2\/types\/legal"}],"version-history":[{"count":0,"href":"https:\/\/www.bloomreach.com\/de\/wp-json\/wp\/v2\/legal\/2250\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.bloomreach.com\/de\/wp-json\/wp\/v2\/media?parent=2250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}