{"id":7611,"date":"2024-04-24T12:00:43","date_gmt":"2024-04-24T12:00:43","guid":{"rendered":"https:\/\/www.bloomreach.com\/case_study\/grandvision-geht-mit-bloomreach-und-commercetools-in-die-digitale-zukunft"},"modified":"2024-06-04T14:53:51","modified_gmt":"2024-06-04T14:53:51","slug":"grandvision-case-study","status":"publish","type":"case_study","link":"https:\/\/www.bloomreach.com\/de\/case-studies\/grandvision-case-study","title":{"rendered":"GrandVision geht mit Bloomreach und commercetools in die digitale Zukunft"},"content":{"rendered":"<p><a href=\"https:\/\/www.grandvision.com\/\" target=\"_blank\" rel=\"noopener\">GrandVision<\/a> ist ein weltweit f\u00fchrender Optik-Einzelh\u00e4ndler mit mehr als 7.200 Gesch\u00e4ften weltweit und einer wachsenden Online-Pr\u00e4senz. Der Optik-H\u00e4ndler bietet Kunden kompetente Augenpflege-Dienstleistungen sowie eine gro\u00dfe Auswahl an stilvollen Brillen, Sonnenbrillen, Kontaktlinsen und anderen Augenpflegeprodukten. Die Gesch\u00e4fte werden unter bekannten lokalen Einzelhandelsmarken betrieben, von denen einige auf mehr als 100 Jahre Geschichte zur\u00fcck blicken.<\/p>\n<p>GrandVision wei\u00df, wie wichtig es ist, eine klare Vorstellung von der Zukunft zu haben. Die etablierten Marken Vision Express, Pearle, Eye Wish, Apollo-Optik, Synoptik und GrandOptical sind weltweit f\u00fchrend im Optik-Einzelhandel und helfen Millionen Kunden, jeden Tag klarer zu sehen.<\/p>\n","protected":false},"author":1,"featured_media":80704,"template":"","industry":[493,82],"channel":[538,534,277,536,544],"class_list":["post-7611","case_study","type-case_study","status-publish","has-post-thumbnail","hentry","channel-ergebnisseiten","channel-kategorieseiten","channel-product-pages","channel-produktseiten","channel-website"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.bloomreach.com\/de\/wp-json\/wp\/v2\/case_study\/7611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bloomreach.com\/de\/wp-json\/wp\/v2\/case_study"}],"about":[{"href":"https:\/\/www.bloomreach.com\/de\/wp-json\/wp\/v2\/types\/case_study"}],"author":[{"embeddable":true,"href":"https:\/\/www.bloomreach.com\/de\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/www.bloomreach.com\/de\/wp-json\/wp\/v2\/case_study\/7611\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bloomreach.com\/de\/wp-json\/wp\/v2\/media\/80704"}],"wp:attachment":[{"href":"https:\/\/www.bloomreach.com\/de\/wp-json\/wp\/v2\/media?parent=7611"}],"wp:term":[{"taxonomy":"industry","embeddable":true,"href":"https:\/\/www.bloomreach.com\/de\/wp-json\/wp\/v2\/industry?post=7611"},{"taxonomy":"channel","embeddable":true,"href":"https:\/\/www.bloomreach.com\/de\/wp-json\/wp\/v2\/channel?post=7611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}